{"id":9333,"date":"2018-05-30T08:17:22","date_gmt":"2018-05-30T06:17:22","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=9333"},"modified":"2018-05-30T08:17:22","modified_gmt":"2018-05-30T06:17:22","slug":"industrie-4-0-nicht-ohne-ausbildung-4-0","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/industrie-4-0-nicht-ohne-ausbildung-4-0\/","title":{"rendered":"Industrie 4.0 nicht ohne Ausbildung 4.0"},"content":{"rendered":"<p>Vom fahrerlosen Transportsystem \u00fcber Roboter- und Automatisierungstechnik bis zu digital vernetzten Maschinen: Das \u201eZukunftsprojekt Industrie 4.0\u201c ist l\u00e4ngst nicht mehr nur Zukunft. Die Digitalisierung h\u00e4lt immer mehr Einzug in Produktion und Fertigung. Neben der technologischen Entwicklung spielt aber auch die Aus- und Weiterbildung der Mitarbeiter eine zentrale Rolle f\u00fcr zukunftsorientierte Unternehmen. Doch wie sieht der \u201eMitarbeiter der Zukunft\u201c aus? Und was bedeutet das f\u00fcr die Ausbildung?<\/p>\n<p>Mit diesen Fragen besch\u00e4ftigt sich eine Veranstaltung des Berufsbildungszentrums (bbz) der IHK Siegen am Dienstag, den 05.06.2018 von 13:30 \u2013 16:30 Uhr. Mit G\u00e4sten aus Bildung und Wirtschaft wird sich die Veranstaltung dem Thema der Digitalisierung in der Ausbildung n\u00e4hern. Ausgehend von der Frage, inwiefern sich Wissensvermittlung und Ausbildung ver\u00e4ndern, bildet die Qualifizierung von Ausbildern und Auszubildenden einen Schwerpunkt. Am Beispiel eines Unternehmens aus der Region, werden praktische Methoden, Konzepte und digitale Medien zur Wissensvermittlung in der Ausbildung vorgestellt. Anschlie\u00dfend beraten und informieren Mitarbeiter des bbz \u00fcber neue Qualifizierungsangebote im Bereich der Digitalisierung. Vom 3D-Druck \u00fcber Prozessintegration bis zur \u201eDigitalisierung der Arbeit\u201c werden u.a. neue Kern- und Zusatzqualifikationen f\u00fcr Auszubildende im Rahmen der Teilnovellierung der M+E-Berufe vorgestellt.<\/p>\n<p>Den Rahmen dieser Veranstaltung bildet das bbz-Projekt \u201eAusbildung 4.0 Siegen-Wittgenstein\u201c, das als JOBSTARTER plus-Projekt aus Mitteln des Bundesministeriums f\u00fcr Bildung und Forschung und des Europ\u00e4ischen Sozialfonds gef\u00f6rdert wird. Hierbei unterst\u00fctzen die Projektmitarbeiter kleine und mittelst\u00e4ndische Unternehmen bei der Sicherung des Fachkr\u00e4ftebedarfs. Durch die Etablierung von Zusatzqualifikationen in der dualen Ausbildung soll diese insbesondere f\u00fcr leistungsstarke Jugendliche attraktiver gestaltet werden. Unternehmen k\u00f6nnen ihre Auszubildenden passgenau und bedarfsgerecht qualifizieren und ihnen Perspektiven im eigenen Unternehmen aufzeigen.<\/p>\n<p>Anmeldung zur Veranstaltung im Berufsbildungszentrum (bbz), Birlenbacher H\u00fctte 10, 57078 Siegen bei: Claudia Erickson (0271 89057-22; <a href=\"mailto:ausbildung40@bbz-siegen.de\" target=\"_blank\" rel=\"noopener\">ausbildung40@bbz-siegen.de<\/a>). Weitere Infos unter: <a href=\"http:\/\/www.bbz-siegen.de\" target=\"_blank\" rel=\"noopener\">www.bbz-siegen.de<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vom fahrerlosen Transportsystem \u00fcber Roboter- und Automatisierungstechnik bis zu digital vernetzten Maschinen: Das \u201eZukunftsprojekt Industrie 4.0\u201c ist l\u00e4ngst nicht mehr nur Zukunft. Die Digitalisierung h\u00e4lt&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16,8,32,30,34],"tags":[],"class_list":["post-9333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeitsmarkt","category-ausbildung","category-infos","category-vermischtes","category-termine"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2016\/08\/bbz-gebaeude_homepage.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/9333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=9333"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/9333\/revisions"}],"predecessor-version":[{"id":9334,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/9333\/revisions\/9334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/4490"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=9333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=9333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=9333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}