{"id":5771,"date":"2017-02-23T08:25:32","date_gmt":"2017-02-23T07:25:32","guid":{"rendered":"http:\/\/www.vdsm.net\/wronline\/?p=5771"},"modified":"2017-02-23T08:25:32","modified_gmt":"2017-02-23T07:25:32","slug":"spende-fuer-hilfsbeduerftige-kinder","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/spende-fuer-hilfsbeduerftige-kinder\/","title":{"rendered":"Spende f\u00fcr hilfsbed\u00fcrftige Kinder"},"content":{"rendered":"<p>Die Unterst\u00fctzung wohlt\u00e4tiger Organisationen in der Region und dar\u00fcber hinaus hat bei der <a href=\"http:\/\/www.siegenia.com\" target=\"_blank\">SIEGENIA-AUBI KG<\/a> in Wilnsdorf eine lange Tradition. Jetzt machten sich die Auszubildenden des Unternehmens erneut f\u00fcr Hilfsbed\u00fcrftige stark. Mit viel pers\u00f6nlichem Engagement und Einsatz initiierten sie eine gro\u00dfe Verkaufsaktion, bei der die Mitarbeiterinnen und Mitarbeiter von SIEGENIA die im Unternehmen eingegangenen Weihnachtspr\u00e4sente zu g\u00fcnstigen Preisen erwerben konnten. Die erfreuliche Bilanz: 240 verkaufte Pr\u00e4sente und ein Erl\u00f6s von rund 1.300 Euro, der von der Unternehmensleitung auf 3.000 Euro aufgestockt wurde.<\/p>\n<p>Grund zur Freude hatte in diesem Jahr der Nachwuchs. Unter den Vorschl\u00e4gen der Mitarbeiter wurden f\u00fcr 2017 drei Organisationen ausgew\u00e4hlt, die durch ihre Arbeit Kindern mit einer starken gesundheitlichen Beeintr\u00e4chtigung und sozial benachteiligten Kindern zu mehr Lebensqualit\u00e4t verhelfen: der F\u00f6rderverein Kinderzuhause Burbach e.V., die SOS-Kinderd\u00f6rfer und die in Wissen ans\u00e4ssige Organisation Kinderarmut in Deutschland e. V., die derzeit die Verlegung ihres Hauptstandorts nach Niederdielfen vorbereitet. Von den Azubis der SIEGENIA GRUPPE erhielten sie nun einen Scheck in H\u00f6he von je 1.000 Euro.<\/p>\n<p>Der F\u00f6rderverein Kinderzuhause Burbach e. V. setzt sich f\u00fcr die Familien von Kindern, Jugendlichen und Erwachsenen mit schweren Mehrfachbehinderungen ein. In seiner Einrichtung \u201eHaus Burgweg\u201c bietet er 28 jungen Menschen mit hohem Pflege- und Betreuungsbedarf ein Zuhause und betreut dort au\u00dferdem eine ambulante Wohngruppe. Der Spendenbetrag tr\u00e4gt u. a. dazu bei, dass im Rahmen der geplanten Sommerfreizeiten Autos gemietet werden k\u00f6nnen, die auch den Transport der Rollst\u00fchle erlauben. Insgesamt hat SIEGENIA dem Verein damit im Laufe der Jahre einen Spendenbetrag in H\u00f6he von insgesamt 12.000 Euro zukommen lassen.<\/p>\n<p>Mit seinen Projekten f\u00fcr mehr als 1.650 Kinder in Not ist der Verein Kinderarmut in Deutschland e. V. in ganz Deutschland aktiv. Von Abenteuerferien im Indianercamp \u00fcber die Erf\u00fcllung individueller Weihnachtsw\u00fcnsche bis zur au\u00dferschulischen F\u00f6rderung finanziert die Organisation j\u00e4hrlich ein breites Spektrum an Ma\u00dfnahmen, die sozial benachteiligten Kindern Wertsch\u00e4tzung und Unterst\u00fctzung signalisieren. Der Spendenbetrag von SIEGENIA wird in die Finanzierung der diesj\u00e4hrigen Sommerurlaube f\u00fcr die Kinder einflie\u00dfen.<\/p>\n<p>Als weltweit aktives Hilfswerk f\u00fcr Kinder machen es sich die SOS-Kinderd\u00f6rfer in weit \u00fcber 100 L\u00e4ndern zur Aufgabe, Not leidenden Kindern den Weg in die Zukunft zu ebnen. In den von ihnen eingerichteten D\u00f6rfern finden verlassene und elternlose Kinder ein neues, stabiles Zuhause. Die in vielen F\u00e4llen angeschlossenen Zusatzeinrichtungen stehen auch bed\u00fcrftigen Kindern und Familien in der Nachbarschaft offen. Mit dem Spendenbetrag unterst\u00fctzt SIEGENIA die Bildungsarbeit, die medizinische Hilfe und die Selbsthilfeprojekte der Vereinigung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Unterst\u00fctzung wohlt\u00e4tiger Organisationen in der Region und dar\u00fcber hinaus hat bei der SIEGENIA-AUBI KG in Wilnsdorf eine lange Tradition. Jetzt machten sich die Auszubildenden&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-5771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unternehmen"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2017\/02\/SIE_Spendenuebergabe_Verkau.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/5771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=5771"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/5771\/revisions"}],"predecessor-version":[{"id":5773,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/5771\/revisions\/5773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/5772"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=5771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=5771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=5771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}