{"id":5084,"date":"2016-11-17T14:11:22","date_gmt":"2016-11-17T13:11:22","guid":{"rendered":"http:\/\/www.vdsm.net\/wronline\/?p=5084"},"modified":"2016-11-21T13:32:09","modified_gmt":"2016-11-21T12:32:09","slug":"feuerverzinkte-stahlbaender-fuer-die-automobilindustrie","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/feuerverzinkte-stahlbaender-fuer-die-automobilindustrie\/","title":{"rendered":"Feuerverzinkte Stahlb\u00e4nder f\u00fcr die Automobilindustrie"},"content":{"rendered":"<p>NUCOR-JFE STEEL MEXICO hat den Auftrag zur Lieferung einer kontinuierlichen Feuerverzinkungslinie und einer Umwickellinie f\u00fcr ein neues Werk in Mexiko an die SMS group <a href=\"http:\/\/www.sms-group.com\/\" target=\"_blank\">(www.sms-group.com)<\/a> vergeben. Die Feuerverzinkungslinie wird 400.000\u00a0Tonnen Stahl\u00adb\u00e4nder pro Jahr produzieren, gr\u00f6\u00dftenteils Tiefziehg\u00fcten und hoch\u00adfeste St\u00e4hle f\u00fcr die Automobilindustrie, inklusive moderner Dual\u00adphasen-St\u00e4hle. Dar\u00fcber hinaus ist die Linie daf\u00fcr ausgelegt, nicht nur Kaltband zu veredeln, sondern auch Warmbandmaterial. Die Inbetriebnahme der Anlage ist f\u00fcr die zweite Jahresh\u00e4lfte 2019 vorgesehen.<\/p>\n<p>NUCOR-JFE STEEL MEXICO ist ein 50:50-Joint-Venture zwischen Nucor Corporation, USA, und JFE Steel Corporation, Japan, welches das Werk in Zentralmexiko bauen und betreiben wird, um den Auto\u00admobilmarkt in der Region zu beliefern. Neben Konstruktion und Fertigung des mechanischen Equipments ist auch die komplette Elektrik und Automation im Lieferumfang der SMS group enthalten.<\/p>\n<p>Die Feuerverzinkungslinie ist ausgelegt f\u00fcr B\u00e4nder mit Dicken von 0,4 bis 2,6 Millimetern und Breiten zwischen 800 und 1.880\u00a0Millimetern. In der Prozesssektion werden die B\u00e4nder mit einer Geschwindigkeit von bis zu 180 Metern pro Minute mit Zink beschichtet, wohingegen in Ein- und Auslauf Bandgeschwindigkeiten von bis zu 280 Metern pro Minute erreicht werden k\u00f6nnen. Die verarbeiteten Stahlg\u00fcten sind Baustahl, Tiefziehg\u00fcten und G\u00fcten mit hohen Zugfestigkeiten. Die Oberfl\u00e4chen der B\u00e4nder werden entweder feuerverzinkt oder galvannealed.<\/p>\n<p>Eine Besonderheit der Linie ist die fortschrittliche Ofentechnologie von Drever International, die eine wirtschaftliche Produktion von hochfesten Materialien erm\u00f6glicht. Das sehr effiziente Verbrennungs\u00adsystem verf\u00fcgt \u00fcber Rekuperatorbrenner. Weiterhin besteht der Ofen aus einem leistungsstarken Schnellk\u00fchlsystem mit Gas-Jets, das Aufr\u00fcstungsm\u00f6glichkeiten bietet. Alle Ofenparameter und Coil-Reihenfolgen werden automatisch von einem mathematisch-physi\u00adkalischen Ofenmodell gesteuert.<\/p>\n<p>Die Reinigungssektion besteht aus effizienten vertikalen elektro\u00adlytischen Reinigungs- und Sp\u00fclzellen sowie horizontalen B\u00fcrst\u00admaschinen. Das Dressierger\u00fcst sorgt f\u00fcr eine optimierte Oberfl\u00e4chen\u00adrauigkeit und eine kleine L\u00e4ngenausdehnung. Ein vertikales Roll-Coater-System mit K\u00fchleinrichtungen von Drever wird zur chemi\u00adschen Behandlung der beschichteten Oberfl\u00e4chen eingesetzt.<\/p>\n<p>Insgesamt besteht die neue Feuerverzinkungslinie aus folgenden wesentlichen Komponenten: Einlaufsektion mit zwei Abwickel\u00adhaspeln, Schwei\u00dfmaschine, Einlaufbandspeicher, Reinigungssektion, Strahlrohrofen, Verzinkungssektion mit Zinkkessel, Zwischenband\u00adspeicher, Dressierger\u00fcst, vertikales Roll-Coater-System, Auslauf\u00adbandspeicher, Bes\u00e4umschere, Inspektionssektion, Ein\u00f6lmaschine, fliegende Schere und zwei Aufhaspel.<\/p>\n<p>Der Lieferumfang beinhaltet ebenso eine Umwickel- und Inspektions\u00adlinie. Diese Linie verf\u00fcgt \u00fcber einen Abhaspel, Schwei\u00dfmaschine, Bes\u00e4umschere, Inspektionsstand, Ein\u00f6lmaschine, Querteilschere und Aufwickelhaspel. Sie ist ebenso ausgelegt f\u00fcr B\u00e4nder mit Dicken zwischen 0,4 und 2,6 Millimetern und Breiten von 800 bis 1.880\u00a0Millimetern. Die maximale Liniengeschwindigkeit betr\u00e4gt 300\u00a0Meter pro Minute.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUCOR-JFE STEEL MEXICO hat den Auftrag zur Lieferung einer kontinuierlichen Feuerverzinkungslinie und einer Umwickellinie f\u00fcr ein neues Werk in Mexiko an die SMS group (www.sms-group.com)&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unternehmen"],"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2016\/11\/01_NUCOR-JFE-STEEL-MEXICO.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/5084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=5084"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/5084\/revisions"}],"predecessor-version":[{"id":5086,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/5084\/revisions\/5086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/5085"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=5084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=5084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=5084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}