{"id":4958,"date":"2016-11-02T14:26:42","date_gmt":"2016-11-02T13:26:42","guid":{"rendered":"http:\/\/www.vdsm.net\/wronline\/?p=4958"},"modified":"2016-11-30T10:08:27","modified_gmt":"2016-11-30T09:08:27","slug":"nachfrage-nach-fachkraeften-bleibt-hoch","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/nachfrage-nach-fachkraeften-bleibt-hoch\/","title":{"rendered":"Nachfrage nach Fachkr\u00e4ften bleibt hoch"},"content":{"rendered":"<p><strong>Die Arbeitslosigkeit im Bezirk der Agentur f\u00fcr Arbeit Siegen ist erneut gesunken. Im Oktober waren 121 Personen weniger arbeitslos als im September. Derzeit sind 11.464 Menschen arbeitslos gemeldet. Die Arbeitslosenquote f\u00e4llt von 5,0 auf 4,9 Prozent und ist genauso hoch wie im Oktober 2015.<\/strong><\/p>\n<p>\u201eF\u00fcr Menschen, die einen neuen Job suchen, ist die Situation auf dem Arbeitsmarkt sehr gut. Die Betriebe suchen in gro\u00dfer Zahl Mitarbeiterinnen und Mitarbeiter\u201c, analysiert Dr. Bettina Wolf, Vorsitzende der Gesch\u00e4ftsf\u00fchrung der Agentur f\u00fcr Arbeit Siegen. So hat der Arbeitgeber-Service der Arbeitsagentur im Oktober 1.086 neue Stellen erfasst. Damit sind derzeit 3.009 Arbeitsstellen unbesetzt. Zum Vergleich: vor einem Jahr waren nur 2.466 Arbeitsstellen frei. \u201eIn den vergangenen Monaten hat sich die Arbeitskr\u00e4fte-Nachfrage auf hohem Niveau eingependelt. Abgesehen von saisonalen Schwankungen erwarten wir f\u00fcr die kommenden Monate keinen Einbruch bei der Arbeitskr\u00e4fte-Nachfrage\u201c, prognostiziert Dr. Wolf. Bereits den f\u00fcnften Monat in Folge kann ihre Agentur den Arbeitssuchenden \u00fcber 3.000 freie Stellen in der Region anbieten.<\/p>\n<p>Der Stellenbestand in den Produktions- und Fertigungsberufen ist zum Beispiel um 29 Prozent gestiegen. Besonders auff\u00e4llig ist die Lebensmittelherstellung und -verarbeitung. In dieser Branche sind mit 80 freien Stellen 67 Prozent mehr Stellen unbesetzt als noch vor einem Jahr. Mit 275 freien Stellen sind die Berufschancen in den Maschinen- und Fahrzeugtechnikberufen ebenfalls deutlich gestiegen. Besonders erfolgversprechend f\u00fcr die Jobsuchenden sind auch die Berufe in der Informatik- und IKT-Branche. In dieser Branche sind mehr als doppelt so viele Stellen frei wie vor einem Jahr. Gleiches gilt f\u00fcr die Reinigungsbranche. Sp\u00fcrbar gestiegen ist auch die Nachfrage nach Fachkr\u00e4ften in den Innen- und Ausbauberufen, Verkehr und Logistik sowie den Erziehungs- und hauswirtschaftlichen Berufen.<\/p>\n<p>F\u00fcr viele freie Stellen Suchen die Betriebe Fachkr\u00e4fte. Doch nicht immer passen die Qualifikationen der Arbeitslosen und die Anforderungen \u00fcberein. \u201eUm diesem Ungleichgewicht auf dem Arbeitsmarkt zu begegnen, werden wir im kommenden Jahr noch st\u00e4rker auf Qualifizierung und Weiterbildung von Arbeitslosen und Arbeitnehmern setzen\u201c, k\u00fcndigt Dr. Bettina Wolf an und wirbt f\u00fcr die Angebote der Arbeitsagentur. Die Agentur finanziert zum Beispiel geringqualifizierten Arbeitslosen und Arbeitnehmern Fortbildungen und Umschulungen, damit sie einen anerkannten Berufsabschluss machen k\u00f6nnen. Auch Teilqualifikationen werden von der Agentur gef\u00f6rdert. \u201eMit der richtigen Qualifizierung kann der Arbeitnehmer seine beruflichen Chancen deutlich verbessern. Und der Arbeitgeber bekommt eine neue Fachkraft\u201c, verdeutlicht Dr. Wolf die Vorteile f\u00fcr beide Seiten.<\/p>\n<p><strong>Arbeitslosigkeit im Rechtskreis der Jobcenter sinkt weiter<\/strong><br \/>\nDie Arbeitslosigkeit im Zust\u00e4ndigkeitsbereich der beiden Jobcenter Kreis SiegenWittgenstein und Kreis Olpe (SGB II) ist weiter gesunken. Mit 7.282 M\u00e4nnern und Frauen waren 24 weniger arbeitslos als im September. Im Oktober 2015 waren 144 arbeitslose Menschen mehr auf Leistungen der Jobcenter angewiesen. Die Zahl der Langzeitarbeitslosen ist im Vergleich zum Vorjahr um 426 gesunken und betr\u00e4gt nun 3.930 Personen. Im Rechtskreis der Agentur f\u00fcr Arbeit Siegen (SGB III) sinkt die Zahl arbeitsloser Menschen um 97 auf 4.128 Personen.<\/p>\n<p><strong>Arbeitslosenquote sinkt im Kreis Siegen-Wittgenstein auf 5,3 Prozent\u00a0<\/strong><br \/>\nIm Oktober waren in Siegen-Wittgenstein 8.216 Menschen ohne Arbeit, das sind 115 weniger als im September, jedoch 67 mehr als im Oktober 2015. Die Arbeitslosenquote sinkt um 0,1 Prozentpunkte auf 5,3 Prozent und ist genauso hoch wie im letzten Jahr. Von den Arbeitslosen sind 5.499 Personen Kunden des Jobcenters Kreis Siegen-Wittgenstein. Das sind 39 Personen weniger als im September und 36 weniger als letztes Jahr im Oktober.<\/p>\n<p><strong>Im Kreis Olpe stagniert die Arbeitslosigkeit auf niedrigem Niveau<\/strong><br \/>\nDie Zahl der Arbeitslosen ist im Kreis Olpe im Oktober um 6 Personen auf 3.248 Menschen gesunken. Auf die Arbeitslosenquote wirkt sich dies nicht aus. Sie liegt weiter bei 4,1 Prozent. Vor einem Jahr lag sie bei 4,0 Prozent. Das Jobcenter Kreis Olpe betreute im Oktober 1.783 Arbeitslose. Das sind 15 Personen mehr als im September, jedoch 108 weniger als im letzten Jahr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Arbeitslosigkeit im Bezirk der Agentur f\u00fcr Arbeit Siegen ist erneut gesunken. Im Oktober waren 121 Personen weniger arbeitslos als im September. Derzeit sind 11.464&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[],"class_list":["post-4958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeitsmarkt"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2015\/12\/Dr_Bettina_Wolf_14.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/4958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=4958"}],"version-history":[{"count":3,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/4958\/revisions"}],"predecessor-version":[{"id":4961,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/4958\/revisions\/4961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/2999"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=4958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=4958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=4958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}