{"id":4822,"date":"2016-10-12T08:27:56","date_gmt":"2016-10-12T06:27:56","guid":{"rendered":"http:\/\/www.vdsm.net\/wronline\/?p=4822"},"modified":"2016-10-12T08:27:56","modified_gmt":"2016-10-12T06:27:56","slug":"suedwestfalen-will-den-heimvorteil-nutzen","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/suedwestfalen-will-den-heimvorteil-nutzen\/","title":{"rendered":"S\u00fcdwestfalen will den &#8222;Heimvorteil&#8220; nutzen"},"content":{"rendered":"<p>\u201eMein Herz schl\u00e4gt f\u00fcr das Sauerland\u201c, \u201ef\u00fcr das Siegerland\u201c, \u201ef\u00fcr Wittgenstein\u201c, f\u00fcr den \u201eKreis Soest\u201c oder einfach \u201ef\u00fcr meine Stadt\u201c. Das ist das Credo vieler junger Menschen, die in der Region aufwachsen. Und diese Verbindung sollte nicht abrei\u00dfen, finden die Verantwortlichen des Regionalmarketings S\u00fcdwestfalen. Das Regionalmarketing-Projekt \u201eHEIMVORTEIL \u2013 Dein Karrierenetzwerk\u201c baut dazu seit einigen Monaten ein wertvolles R\u00fcckkehrer-Netzwerk auf.<\/p>\n<p>Denn: Jeder Dritte zwischen 18 und 25 Jahren verl\u00e4sst S\u00fcdwestfalen f\u00fcr ein Studium oder den Job. Umso wichtiger ist es daher, den jungen Studenten und Fachkr\u00e4ften, die au\u00dferhalb der Region leben und arbeiten, den Schritt des Wiederkommens zu erleichtern. Von Burbach bis Lippstadt, von Halver bis Marsberg \u2013 \u201eR\u00fcckkehrer\u201c in die Heimat sind \u00fcberall gerne gesehen. Ob g\u00fcnstige Miet- und Kaufpreise von Immobilien, interessante Job-Angebote, privates Netzwerk oder das entspannte und staufreie Leben im Gr\u00fcnen: Viele, die die Region verlassen, lernen die besonderen Vorteile der eigenen Heimat dann zu sch\u00e4tzen, wenn sie das Leben in Metropolen kennengelernt haben. Die Heimat bleibt wichtig und das Verlangen, zur\u00fcckzukehren, oftmals ein inniger Wunsch.<\/p>\n<p>\u201eBei der Frage, welche Menschen wir eigentlich f\u00fcr die Arbeitspl\u00e4tze und einen Umzug in die Region begeistern k\u00f6nnen, liegt der Gedanke an R\u00fcckkehrer nat\u00fcrlich nahe\u201c, so Marie Ting, Regionalmarketing Managerin der S\u00fcdwestfalen Agentur GmbH. Sie leitet den Prozess des Regionalmarketings im Auftrag von Politik und Wirtschaft. Das Ziel: Mit attraktiver Werbung f\u00fcr die Region dem drohenden Fachkr\u00e4ftemangel entgegenzuwirken. \u201eDabei sind wir weit davon entfernt, mit teuren und kurzlebigen Plakataktionen viel Geld f\u00fcr nichts zu verschleudern.\u201c Stattdessen gehe es um den klugen Aufbau von Strukturen, regionale Zusammenarbeit \u2013 und die gemeinsame Bewusstseins-Bildung der starken Region und ihren Kernmarken: Sauerland und Siegerland-Wittgenstein in S\u00fcdwestfalen.<\/p>\n<p>Was etwas abstrakt klingen mag, wird anhand des Themas \u201eR\u00fcckkehrer\u201c schnell plastisch: Gemeinsam mit den Wirtschaftsf\u00f6rderungen des Hochsauerlandkreises und des Kreises Soest wurde das Thema detailliert durchdacht. \u201eStatt ganz S\u00fcdwestfalen als Experimentierlabor zu \u00fcberfordern, haben wir gemeinsam beschlossen, zun\u00e4chst im Hochsauerlandkreis das Modellprojekt \u201eHEIMVORTEIL HSK\u201c f\u00fcr R\u00fcckkehrer aufzusetzen\u201c, so Ting. \u201eSo schlagen wir zwei Fliegen mit einer Klappe: Erstens k\u00f6nnen wir so in einer kleineren Region erste Erfahrungen sammeln. Und zweitens sprechen wir damit gezielt R\u00fcckkehrer entsprechend ihrer Heimat-Identit\u00e4t, in diesem Falle \u201eSauerland\u201c, an. Dabei stellen wir im Sinne der \u201eS\u00fcdwestfalen \u2013 Alles echt!\u201c-Kampagne die Vorteile der gesamten Region und die attraktiven Arbeitgeber im einheitlichen und ansprechenden S\u00fcdwestfalen-Design vor.\u201c Zu einem sp\u00e4teren Zeitpunkt sollen die guten Erfahrungen des Projekts dann auf die anderen s\u00fcdwestf\u00e4lischen Kreise \u00fcbertragen werden: Von Burbach bis Lippstadt, von Halver bis Marsberg. Dieses Konzept \u00fcberzeugte sogar \u00fcberregional: Das Projekt wird aus Bundesmitteln\u00a0des Bundesministerium f\u00fcr Ern\u00e4hrung und Landwirtschaft finanziell gef\u00f6rdert. M\u00f6glich wurde dies durch eine erfolgreiche Bewerbung des HSK im Rahmen des bundesweiten Modellvorhabens &#8222;Land(auf)schwung&#8220;.<\/p>\n<p>Doch wie genau will man nun die R\u00fcckkehrer erreichen? \u201eIndem wir junge Menschen ganz einfach und emotional dort abholen, wo sie sind\u201c, lautet die Antwort von Marie Ting.\u00a0Dazu ist Sandra Schmitt seit Beginn des Jahres 2016 f\u00fcr die Umsetzung des Projektes bei der Wirtschaftsf\u00f6rderung Hochsauerlandkreis mbH zust\u00e4ndig. Passenderweise ist sie selbst ebenfalls: R\u00fcckkehrerin. Sie berichtet: \u201eIn diesem Jahr ist schon unheimlich viel passiert. Unter anderem haben wir auf zw\u00f6lf Sch\u00fctzenfesten im Sauerland mit einer Fotoaktion auf das Projekt aufmerksam gemacht \u2013 schlie\u00dflich bleibt das Sch\u00fctzenfest Magnet f\u00fcr viele, die hier aufgewachsen sind. Au\u00dferdem haben knapp 2.000 Abiturienten und Studenten der FH S\u00fcdwestfalen, Standort Meschede, in diesem Jahr die \u201eHEIMVORTEIL2Go-Boxen\u201c erhalten, die Produkte von heimischen Unternehmen beinhaltet.\u201c Immer dabei: Die Einladung, der Facebook-Seite des Projektes zu folgen. Mit Eintr\u00e4gen zu attraktiven Karrierem\u00f6glichkeiten, Jobangeboten und News zur Region bleiben potenzielle R\u00fcckkehrer somit ganz locker mit ihrer Heimat in Verbindung. Spricht man mit Sandra Schmitt wird schnell klar: An Ideen zur Vereinfachung der R\u00fcckkehr mangelt es nicht. Auch die Nachfrage und Resonanz auf die bisherigen Aktionen seien durchweg positiv, so Schmitt.<\/p>\n<p>Ein besonderes Bonbon: Bei Interesse an einer R\u00fcckkehr steht Sandra Schmitt als Ansprechpartnerin des Willkommen-Netzwerkes ganz pers\u00f6nlich mit Rat und Tat zur Verf\u00fcgung, organisiert R\u00fcckkehrer-Stammtische und leitet interessante Bewerbungen von R\u00fcckkehrern in das s\u00fcdwestf\u00e4lische Netzwerk weiter. \u201eGenau das ist meine Mission\u201c, so Schmitt. \u201eWir wollen m\u00f6glichst viele Menschen mit einem inneren Gummiband ausstatten und bei der R\u00fcckkehr begleiten.\u201c Sie selbst habe den Schritt zur\u00fcck nicht bereut \u2013im Gegenteil. Schritt zur\u00fcck? \u201eNein, zur\u00fcck \u2013 und somit nach vorne\u201c, lacht Schmitt.<\/p>\n<p>\u201eHEIMVORTEIL ist ein echtes Mitmachprojekt, das jetzt schon erste echte Erfolge vorweisen kann\u201c, freut sich Marie Ting. In den n\u00e4chsten Monaten soll das Modellprojekt weiter ausgebaut und regelm\u00e4\u00dfig evaluiert werden. F\u00fcr sie steht fest: \u201eDie Unternehmen, die sich im Verein \u201eWirtschaft f\u00fcr S\u00fcdwestfalen\u201c f\u00fcr das Regionalmarketing engagieren, werden von diesem R\u00fcckkehrer-Netzwerk nat\u00fcrlich zuk\u00fcnftig sehr konkret profitieren. Beispielsweise durch den Zugriff auf Bewerber, die gezielt in die Region zur\u00fcckkommen m\u00f6chten.\u201c<\/p>\n<p>Zur gleichen Zeit wird bei der wfg Wirtschaftsf\u00f6rderungsgesellschaft Kreis Soest mbH ein Schwester-Projekt gestartet. Dabei liegt der \u201eHeimvorteil\u201c-Schwerpunkt auf dem Aspekt der Sicherstellung der haus\u00e4rztlichen Grundversorgung. Im Rahmen einer Gesamtstrategie zur individuellen Unterst\u00fctzung interessierter Mediziner sollen Netzwerktreffen und Social-Media-Kan\u00e4le den Kontakt zur Zielgruppe aufbauen: Sch\u00fclerinnen und Sch\u00fcler aus dem Kreis Soest, die ein Medizinstudium anstreben, sowie Medizinstudierende, die aus dem Kreis Soest stammen. Erfahrungen aus dem Projekt werden erneut s\u00fcdwestf\u00e4lisch zusammengetragen. Das Willkommensnetzwerk der Region w\u00e4chst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eMein Herz schl\u00e4gt f\u00fcr das Sauerland\u201c, \u201ef\u00fcr das Siegerland\u201c, \u201ef\u00fcr Wittgenstein\u201c, f\u00fcr den \u201eKreis Soest\u201c oder einfach \u201ef\u00fcr meine Stadt\u201c. Das ist das Credo vieler&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[30,11],"tags":[],"class_list":["post-4822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vermischtes","category-regionale-wirtschaft"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2016\/10\/Pressefoto_Heimvorteil_3000.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/4822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=4822"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/4822\/revisions"}],"predecessor-version":[{"id":4824,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/4822\/revisions\/4824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/4823"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=4822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=4822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=4822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}