{"id":33437,"date":"2025-11-06T09:23:05","date_gmt":"2025-11-06T08:23:05","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=33437"},"modified":"2025-11-06T11:13:29","modified_gmt":"2025-11-06T10:13:29","slug":"kriegstuechtigkeit-informationen-aus-erster-hand","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/kriegstuechtigkeit-informationen-aus-erster-hand\/","title":{"rendered":"&#8222;Kriegst\u00fcchtigkeit&#8220;: Informationen aus erster Hand"},"content":{"rendered":"<p>\u201eVertrauen Sie der Bundeswehr. Wir werden Sie sch\u00fctzen!\u201c Bei allen anstehenden Herausforderungen f\u00fcr die Vorbereitungen auf den Verteidigungsfall machte Oberst Jens Dobrindt den mehr als 100 Besuchern beim Wittgensteiner Wirtschaftstreff Mut. Der Kommandeur des Einsatzbereiches 2 und Standort\u00e4lteste am Bundeswehr-Standort Erndtebr\u00fcck gab einen Einblick in das Thema \u201eKriegst\u00fcchtigkeit\u201c am Beispiel des Luftwaffenstandortes und zeigte die milit\u00e4rische Perspektive auf. \u201eSoldaten allein reichen nicht aus, um das Land zu verteidigen. Gerade, wenn es um die Rolle Deutschlands als logistische Drehscheibe f\u00fcr die NATO geht, kommt es auch auf die Unternehmen in der Breite und die B\u00fcrger an!\u201c<\/p>\n<p>Sollte der B\u00fcndnisfall eintreten, also das Gebiet der NATO angegriffen werden, m\u00fcssten rund 800.000 Soldaten mit Ausr\u00fcstung in Richtung Osten verlegt werden \u2013 eine gewaltige logistische Herausforderung, f\u00fcr die schon heute Vorkehrungen zu treffen seien. Autobahnen und Schienenstrecken m\u00fcssten in diesem Fall gesperrt werden, Soldaten m\u00fcssten versorgt, \u00dcbernachtungsm\u00f6glichkeiten bereitgestellt und Lagerkapazit\u00e4ten f\u00fcr Produkte vorgehalten werden. Daf\u00fcr bed\u00fcrfe es etwas, das in Wittgenstein geradezu pr\u00e4gend sei: Zusammenhalt.<\/p>\n<p>In der Lagebeschreibung w\u00e4hlte der Referent klare Worte: \u201eUnser Gegner ist Russland.\u201c Die Bundeswehr richte sich auf eine milit\u00e4rische Intervention auf NATO-Gebiet ein, damit diese abgewendet werden k\u00f6nne. Detailliert ging Dobrindt auf verschiedene m\u00f6gliche Bedrohungslagen entlang der Ostflanke der NATO ein. Er verdeutlichte, welche weitreichenden Folgen bestimmte milit\u00e4rische Angriffe nach sich z\u00f6gen. Russland habe seine gesamte Wirtschaft l\u00e4ngst auf Kriegswirtschaft umgestellt.<\/p>\n<p>Analysten gingen davon aus, dass Russland 2029 milit\u00e4risch in der Lage sein werde, neben dem Ukraine-Krieg in einen weiteren Konflikt zu treten, der das Baltikum treffen k\u00f6nnte. \u201eOb das passieren wird, wissen wir nicht. Aber wir m\u00fcssen darauf vorbereitet sein.\u201c Darum gehe es bei der Herstellung von Kriegst\u00fcchtigkeit. Sie bedeute, f\u00fcr einen und in einem Krieg in jeglicher Hinsicht gut ger\u00fcstet zu sein. Potenzielle Aggressoren sollen hierdurch abgeschreckt werden.<\/p>\n<p>Die j\u00fcngsten kriegerischen Auseinandersetzungen auf dem Globus h\u00e4tten gezeigt, welchen Einfluss der Einsatz von Drohnen als \u00dcberwachungsinstrument oder Angriffswaffe habe. \u201eDas f\u00fchrt dazu, dass bisherige Strategien \u00fcberdacht werden m\u00fcssen. Hier d\u00fcrfen wir den Anschluss nicht verpassen.\u201c Die Bedrohungslage sei inzwischen l\u00e4ngst auch in der Wirtschaft und in Privathaushalten sp\u00fcrbar, etwa durch Cyberattacken oder Fake News, die darauf ausgerichtet seien, einen Keil zwischen B\u00fcrgern, Regierung und der Bundeswehr zu treiben.<\/p>\n<div id=\"attachment_33439\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Gruppenfoto-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33439\" class=\"size-medium wp-image-33439\" src=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Gruppenfoto-300x211.jpg\" alt=\"\" width=\"300\" height=\"211\" srcset=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Gruppenfoto-300x211.jpg 300w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Gruppenfoto-1024x721.jpg 1024w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Gruppenfoto-768x541.jpg 768w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Gruppenfoto-1536x1082.jpg 1536w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Gruppenfoto-2048x1442.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-33439\" class=\"wp-caption-text\">Die Veranstalter des Wirtschaftstreff mit Oberst Jens Dobrindt (3.v.r.).<\/p><\/div>\n<p>Sollte es zu einer Truppenbewegung kommen, seien die Soldaten am Standort Erndtebr\u00fcck von dieser nicht unmittelbar betroffen, sodass der Luftraum \u00fcber Deutschland durch das hochqualifizierte Personal weiter rund um die Uhr \u00fcberwacht werden kann. Im Verteidigungsfall seien aber auch Fragen im Zivilschutz zu kl\u00e4ren. So m\u00fcssten Kapazit\u00e4ten in Krankenh\u00e4usern bereitgestellt und unter anderem gen\u00fcgend Blutkonserven vorgehalten werden. Eindringlich warb Jens Dobrindt vor diesem Hintergrund f\u00fcr einen engeren Austausch zwischen Bundeswehr und Bev\u00f6lkerung, aber auch dem Zivilschutz, wobei er sich ausdr\u00fccklich auch selbst in die Plicht nahm. Hinreichend Gelegenheit dazu gibt es nicht zuletzt im kommenden Jahr, wenn der Luftwaffen-Standort Erndtebr\u00fcck sein 60-j\u00e4hriges Bestehen feiert.<\/p>\n<p>Der Vortrag bot viel Stoff f\u00fcr Diskussionen im Anschluss. Musikalisch wurde der Wittgensteiner Wirtschaftstreff durch den Auftritt des Singer-Songwriters \u201eMyller\u201c aus Gie\u00dfen umrahmt. Veranstalter waren erneut neben dem Autohaus M\u00fcller die Arbeitgeberverb\u00e4nde Siegen-Wittgenstein, die Sparkasse Wittenstein, die Volksbank Wittgenstein, die Kreishandwerkerschaft Westfalen-S\u00fcd und die IHK Siegen.<\/p>\n<p>Fotos\/Text: IHK Siegen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eVertrauen Sie der Bundeswehr. Wir werden Sie sch\u00fctzen!\u201c Bei allen anstehenden Herausforderungen f\u00fcr die Vorbereitungen auf den Verteidigungsfall machte Oberst Jens Dobrindt den mehr als&#8230;<\/p>\n","protected":false},"author":7,"featured_media":33438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,30],"tags":[],"class_list":["post-33437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-vermischtes"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/11\/069-25-Wittgensteiner-Wirtschaftstreff-Jens-Dobrindt-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/33437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=33437"}],"version-history":[{"count":2,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/33437\/revisions"}],"predecessor-version":[{"id":33441,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/33437\/revisions\/33441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/33438"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=33437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=33437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=33437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}