{"id":33179,"date":"2025-06-27T15:52:05","date_gmt":"2025-06-27T13:52:05","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=33179"},"modified":"2025-06-30T10:20:32","modified_gmt":"2025-06-30T08:20:32","slug":"osterrath-gmbh-co-kg-spannende-eindruecke-beim-tag-der-offenen-tuer","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/osterrath-gmbh-co-kg-spannende-eindruecke-beim-tag-der-offenen-tuer\/","title":{"rendered":"Osterrath GmbH &#038; Co. KG: Spannende Eindr\u00fccke beim Tag der offenen T\u00fcr"},"content":{"rendered":"<div id=\"attachment_33182\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/06\/EL3A0010-scaled-e1751032131996.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33182\" class=\"wp-image-33182 size-medium\" src=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/06\/EL3A0010-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><p id=\"caption-attachment-33182\" class=\"wp-caption-text\">In diesem Jahr begeht die Osterrath GmbH &amp; Co. KG ihr 175-j\u00e4hriges Firmenjubil\u00e4um.<\/p><\/div>\n<p>Anl\u00e4sslich ihres 175-j\u00e4hriges Firmenjubil\u00e4um hat die Osterrath GmbH &amp; Co. KG zu einem Tag der offenen T\u00fcr eingeladen. Noch bis 17.30 Uhr haben G\u00e4ste heute, am Freitag 27. Juni 2025, Zeit und k\u00f6nnen zum Firmensitz nach Bad Laasphe-Sa\u00dfmannshausen kommen und einen Blick hinter die Kulissen werfen.<\/p>\n<p>Geboten werden unter anderem informative Werksf\u00fchrungen, die spannende Einblicke, starke Maschinen und Technik zum Anfassen bieten. Vertriebsleiter Patrick Sa\u00dfmann ist einer derjenigen, der den Besuchern w\u00e4hrend einer F\u00fchrung einen Blick hinter die Kulissen bietet. Von ihm erfahren die G\u00e4ste u.a., dass die Gr\u00fcndung des Unternehmens im Jahre 1850 in Wuppertal war. Ein Brand zerst\u00f6rte damals das Werk dort im Bergischen, sodass es zu einem Neuaufbau in Bad Laasphe-Sa\u00dfmannshausen kam. Profiteur des Wirtschaftswunders war die Produktion f\u00fcr Radio-, TV-,Leiterplatten-\/Elektroindustrie. Heute hingegen ist die st\u00e4rkste Branche Automotive.<\/p>\n<div id=\"attachment_33183\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/06\/EL3A0013-scaled-e1751032232279.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33183\" class=\"wp-image-33183 size-medium\" src=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/06\/EL3A0013-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><p id=\"caption-attachment-33183\" class=\"wp-caption-text\">Besucherinnen und Besucher beim Tag der offenen T\u00fcr bei Osterrath<\/p><\/div>\n<p>Das Wittgensteiner Unternehmen, welches 180 Mitarbeiter besch\u00e4ftigt fertigt mehr als 2.000 verschiedene Produkte. Zu den Kunden des Unternehmens z\u00e4hlen neben Automotive, die Elektroindustrie, die Batterietechnik, die Medizintechnik sowie die Bautechnik. Dass der R\u00f6ntgenstrahl im R\u00f6ntgenger\u00e4t von einem Osterrath-Bauteil geb\u00fcndelt und wieder gestreut wird, ist nur ein spannender Aspekt, den Patrick Sa\u00dfmann w\u00e4hrend der F\u00fchrung erz\u00e4hlt.<\/p>\n<p>Dass im Unternehmen alle Werkzeuge selbst gebaut werden und nichts gekauft wird, wird anhand der Abteilung Werkzeugbau auf eindrucksvolle Weise sichtbar. Neben dieser Abteilung haben die G\u00e4ste w\u00e4hrend der rund 45-min\u00fctigen F\u00fchrungen allerhand Gelegenheit die verschiedenen Abteilungen der Osterrrath GmbH &amp; Co. KG kennenzulernen. Werkzeugbau, Stanzerei, Materiallager, B\u00fcroarbeitspl\u00e4tze, etc. &#8211; es gibt beim Tag der offenen T\u00fcr reichlich Gelegenheiten das Unternehmen hautnah zu erleben.<\/p>\n<div id=\"attachment_33184\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/06\/EL3A0014-scaled-e1751032292293.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33184\" class=\"wp-image-33184 size-medium\" src=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/06\/EL3A0014-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><p id=\"caption-attachment-33184\" class=\"wp-caption-text\">Zahlreiche G\u00e4ste sind gekommen, um einen Blick hinter die Kulissen des Unternehmens zu werfen.<\/p><\/div>\n<p>Neben all den R\u00e4umlichkeiten wird den Besucherinnen und Besuchern schnell klar, dass sich das Unternehmen auch im Punkto &#8222;Umwelt&#8220; starkmacht. Eine PV-Anlage sorgt u.a. daf\u00fcr, dass etwa ein Drittel des vom Unternehmen ben\u00f6tigten Stroms selbst produziert wird. Ein weiteres Highlight sind die Osterrath-Bienen, sodass das Unternehmen auch Honig produziert, dessen Gl\u00e4ser beim Tag der offenen T\u00fcr verschenkt werden.<\/p>\n<p>Neben allerhand informativen rund ums Unternehmen kommen auch der Spa\u00df und der Genuss nicht zu kurz. Torwandschie\u00dfen, Kinderschminken, ebenso wie beispielsweise Foodtrucks und k\u00fchle Getr\u00e4nke sorgen daf\u00fcr, dass die G\u00e4ste gerne beim Wittgensteiner Unternehmen verweilen und einen Blick hinter die Kulissen werfen.<\/p>\n<p>Text und Fotos: Julia F\u00f6rster<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anl\u00e4sslich ihres 175-j\u00e4hriges Firmenjubil\u00e4um hat die Osterrath GmbH &amp; Co. KG zu einem Tag der offenen T\u00fcr eingeladen. Noch bis 17.30 Uhr haben G\u00e4ste heute,&#8230;<\/p>\n","protected":false},"author":6,"featured_media":33180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,32,30,10],"tags":[],"class_list":["post-33179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-infos","category-vermischtes","category-unternehmen"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2025\/06\/EL3A0006-scaled-e1751030524325.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/33179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=33179"}],"version-history":[{"count":3,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/33179\/revisions"}],"predecessor-version":[{"id":33187,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/33179\/revisions\/33187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/33180"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=33179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=33179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=33179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}