{"id":32708,"date":"2024-11-14T16:12:24","date_gmt":"2024-11-14T15:12:24","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=32708"},"modified":"2024-11-14T16:12:24","modified_gmt":"2024-11-14T15:12:24","slug":"nrw-metallarbeitgeber-abschluss-ist-hoch-aber-noch-vertretbar","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/nrw-metallarbeitgeber-abschluss-ist-hoch-aber-noch-vertretbar\/","title":{"rendered":"NRW-Metallarbeitgeber: Abschluss ist hoch, aber noch vertretbar"},"content":{"rendered":"<p>Die Tarifparteien der nordrhein-westf\u00e4lischen Metall- und Elektroindustrie haben den am Dienstag in Hamburg vereinbarten Pilot-Abschluss heute \u00fcbernommen. Der Pr\u00e4sident des Verbandes der Metall- und Elektro-Industrie Nordrhein-Westfalen (METALL NRW), Arndt G. Kirchhoff, sagte nach der vierten Tarifverhandlung f\u00fcr die 700.000 Besch\u00e4ftigten dieses Industriezweigs in Neuss, die Tarifparteien h\u00e4tten ein hohes Ma\u00df an Kompromissbereitschaft und Verantwortungsbewusstsein gezeigt. \u201eWir haben einmal mehr bewiesen, dass die Tarifautonomie gerade in unserer Industrie funktioniert\u201c, betonte Kirchhoff. Angesichts der au\u00dferordentlich schwierigen Wirtschaftslage sei der Abschluss hoch, aber insgesamt gerade noch vertretbar.<\/p>\n<p>Umso wichtiger sei es, dass den Unternehmen f\u00fcr das Jahr 2024 keine weitere zus\u00e4tzliche Belastung bei den tariflichen Arbeitskosten drohe. \u201eUnd f\u00fcr 2025 wird die Tarifsteigerung f\u00fcr die Unternehmen, die das automatische Differenzierungselement des Abschlusses in Anspruch nehmen k\u00f6nnen, weitgehend vermieden werden k\u00f6nnen&#8220;, erkl\u00e4rte der Metallarbeitgeberpr\u00e4sident.<\/p>\n<p>Die Tarifvereinbarung, die l\u00e4nger als zwei Jahre gelte, sorge nun f\u00fcr \u201edringend notwendige Verl\u00e4sslichkeit und Planungssicherheit\u201c. Die M+E-Tarifpartner h\u00e4tten im Ergebnis eine hohe gesellschaftspolitische Verantwortung gezeigt. Umso mehr sei jetzt die Politik gefordert, endlich das Richtige f\u00fcr die St\u00e4rkung der Wettbewerbsf\u00e4higkeit des Industriestandorts Deutschland zu tun. \u201eDa darf jetzt keine Zeit mehr verloren gehen. Weltm\u00e4rkte, Wettbewerber und Investoren nehmen auf den Wahlkampf in Deutschland jedenfalls keine R\u00fccksicht\u201c, sagte Kirchhoff.<\/p>\n<p>Die Ergebnisse im Einzelnen:<\/p>\n<p>\u00b7 Der Tarifvertrag hat eine Laufzeit von 25 Monaten und endet am 31. Oktober 2026.<br \/>\n\u00b7 Im Februar 2025 erhalten die Besch\u00e4ftigten eine Einmalzahlung von 600 Euro, deren Auszahlung freiwillig auch bereits im Jahr 2024 erfolgen kann.<br \/>\n\u00b7 Die Tabellenentgelte erh\u00f6hen sich zum 1. April 2025 um 2,0 Prozent und zum 1. April 2026 um weitere 3,1 Prozent.<br \/>\n\u00b7 Die Auszubildendenverg\u00fctungen steigen ab Januar 2025 in allen Ausbildungsjahren um 140 Euro. Zus\u00e4tzlich werden sie zum 1. April 2026 um 3,1 Prozent erh\u00f6ht.<br \/>\n\u00b7 Ankn\u00fcpfungspunkt der automatischen Differenzierung ist anstelle des sogenannten T-Zug (B) ab 2025 das sogenannte Transformationsgeld, das fortan im Juli eines Jahres ausgezahlt wird. Damit wird das Differenzierungsvolumen erh\u00f6ht und betr\u00e4gt nun 18,4 Prozent eines Monatsentgelts. Dies kann zeitlich geschoben, gek\u00fcrzt oder ganz gestrichen werden, wenn ein Unternehmen eine Nettoumsatzrendite von mindestens 2,3 Prozent nicht erreicht.<br \/>\n\u00b7 Die M\u00f6glichkeit zur Nutzung der Freistellungstage des T-Zug (A) wurde moderat ausgeweitet. Gleichzeitig wurden entsprechende Kompensationsm\u00f6glichkeiten f\u00fcr den Arbeitgeber geschaffen.<\/p>\n<p>Text\/Foto: Metall NRW<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Tarifparteien der nordrhein-westf\u00e4lischen Metall- und Elektroindustrie haben den am Dienstag in Hamburg vereinbarten Pilot-Abschluss heute \u00fcbernommen. Der Pr\u00e4sident des Verbandes der Metall- und Elektro-Industrie&#8230;<\/p>\n","protected":false},"author":7,"featured_media":25985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,180,11],"tags":[],"class_list":["post-32708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-tarifrunde-2024","category-regionale-wirtschaft"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2021\/11\/21-8-20-AGK_Redaktionsbesuc.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=32708"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32708\/revisions"}],"predecessor-version":[{"id":32709,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32708\/revisions\/32709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/25985"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=32708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=32708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=32708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}