{"id":32558,"date":"2024-09-12T09:07:32","date_gmt":"2024-09-12T07:07:32","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=32558"},"modified":"2024-09-12T09:07:32","modified_gmt":"2024-09-12T07:07:32","slug":"zwoelf-auszubildende-starten-ihre-berufliche-zukunft-bei-der-emg-automation-gmbh","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/zwoelf-auszubildende-starten-ihre-berufliche-zukunft-bei-der-emg-automation-gmbh\/","title":{"rendered":"Zw\u00f6lf Auszubildende starten ihre berufliche Zukunft bei der EMG Automation GmbH"},"content":{"rendered":"<p>Anfang September starteten zw\u00f6lf neue Auszubildende ihre berufliche Laufbahn bei der EMG Automation GmbH. Das Unternehmen setzt damit seine langj\u00e4hrige Tradition fort, junge Talente zu f\u00f6rdern und optimal auf die Anforderungen der Industrie vorzubereiten.<\/p>\n<p>Die neuen Auszubildenden werden in verschiedenen technischen und kaufm\u00e4nnischen Berufen ausgebildet \u2013 konkret: Industriemechaniker, Industriekaufmann \/ -kauffrau, Mechatroniker, Elektroniker f\u00fcr Betriebstechnik, Zerspanungsmechaniker, IT-Systemelektroniker und Fachkraft f\u00fcr Lagerlogistik. Die Ausbildung bei der EMG bietet den jungen Nachwuchskr\u00e4ften neben einer fundierten fachlichen Qualifizierung auch die M\u00f6glichkeit, in einem innovativen Arbeitsumfeld wertvolle Praxiserfahrungen zu sammeln.<\/p>\n<p>\u201eWir freuen uns sehr, dass wir zahlreiche junge Menschen f\u00fcr eine Ausbildung bei uns gewinnen und auch in diesem Jahr wieder alle Ausbildungspl\u00e4tze besetzen konnten\u201c, so Alexander Heck, Gesch\u00e4ftsf\u00fchrer der EMG Automation GmbH. \u201eDie F\u00f6rderung und Entwicklung von Nachwuchskr\u00e4ften ist f\u00fcr uns ein zentrales Anliegen. Durch unsere umfangreiche und praxisnahe Ausbildung legen wir den Grundstein f\u00fcr die Fachkr\u00e4fte von morgen und damit unsere Zukunft.\u201c<\/p>\n<p>Seit mehr als 75 Jahren bildet die EMG in der Region aus. Seitdem haben hier rund 1.400 junge Menschen ihre Ausbildung absolviert. Neben gewerblichen-technischen und kaufm\u00e4nnischen Ausbildungsm\u00f6glichkeiten gibt es bei EMG eine eigene Ausbildungswerkstatt, j\u00e4hrliche Auslandspraktika in Irland sowie regelm\u00e4\u00dfige Azubifahrten.<\/p>\n<p>Bereits letzte Woche hatten die neuen Auszubildenden die Chance, die EMG kennenzulernen. Die Jugendlichen bekamen das Unternehmen und die verschiedenen Gesch\u00e4ftsbereiche mit ihren Produkten vorgestellt. Au\u00dferdem erhielten sie zur Vorbereitung schon alle wichtigen Infos rund um ihren Ausbildungsbetrieb. Sie lernten die Ausbildungsbeauftragten aller Fachbereiche kennen und bekamen ihre personalisierte Arbeitskleidung und pers\u00f6nlichen Laptops \u00fcberreicht. Dazu gab es auch Erkl\u00e4rungen zum Umgang mit den Endger\u00e4ten, wie die Berichtsheft-App funktioniert und welche weitere digitalen Lernbegleiter existieren.<\/p>\n<p>Text und Foto: EMG Automation GmbH<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anfang September starteten zw\u00f6lf neue Auszubildende ihre berufliche Laufbahn bei der EMG Automation GmbH. Das Unternehmen setzt damit seine langj\u00e4hrige Tradition fort, junge Talente zu&#8230;<\/p>\n","protected":false},"author":6,"featured_media":32559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8,32,30,10],"tags":[],"class_list":["post-32558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausbildung","category-infos","category-vermischtes","category-unternehmen"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2024\/09\/Neue-EMG-Azubis-2024-scaled-e1726124758708.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=32558"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32558\/revisions"}],"predecessor-version":[{"id":32560,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32558\/revisions\/32560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/32559"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=32558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=32558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=32558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}