{"id":32482,"date":"2024-08-23T15:57:37","date_gmt":"2024-08-23T13:57:37","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=32482"},"modified":"2024-08-23T16:24:27","modified_gmt":"2024-08-23T14:24:27","slug":"mintoringsi-2024-neue-bewerbungsphase-laeuft-bis-zum-30-09-2024","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/mintoringsi-2024-neue-bewerbungsphase-laeuft-bis-zum-30-09-2024\/","title":{"rendered":"MINToringSi 2024: Neue Bewerbungsphase l\u00e4uft bis zum 30.09.2024"},"content":{"rendered":"<p>MINToringSi ist ein Kooperationsprogramm des Verbandes der Siegerl\u00e4nder Metallindustriellen (VdSM), der Universit\u00e4t Siegen und der Bezirksregierung Arnsberg. Das Ziel ist es, junge Menschen f\u00fcr die MINT-F\u00e4cher zu begeistern. Das Programm umfasst die F\u00f6rderung MINT-interessierter Sch\u00fclerinnen und Sch\u00fcler, beginnend ab der Q1.<\/p>\n<p>&#8222;Die letzten Jahre haben gezeigt, dass es m\u00f6glich ist, das Programm\u00a0auch mit der Erg\u00e4nzung durch Online-Formate sinnstiftend zu betreiben&#8220;, sind sich die beiden Programmkoordinatoren Dr. Thomas Reppel (Universit\u00e4t Siegen) und Julia F\u00f6rster (VdSM) einig. Ab sofort l\u00e4uft die neue Bewerbungsphase.<\/p>\n<p><strong>Kurz noch einmal die essentiellen Eckpunkte des Programms:<\/strong><\/p>\n<p>MINToringSi richtet sich an\u00a0Sch\u00fcler:innen der Q1 (erstes Jahr der Qualifikationsphase in der Gymnasialen Oberstufe) der Gymnasien und Gesamtschulen im Kreis Siegen-Wittgenstein, die folgende Randbedingungen erf\u00fcllen:<\/p>\n<ul>\n<li>Vorzugsweise mindestens 1 naturwissenschaftliches Fach und \/ oder Mathematik als Leistungskurs.<\/li>\n<li>Mindestens gute Leistungen in Mathematik.<\/li>\n<li>Leistungsstarke\u00a0Sch\u00fcler:innen, die andere Leistungskurse belegen, aber dennoch an MINT-F\u00e4chern interessiert sind, k\u00f6nnen sich ebenfalls bewerben.<\/li>\n<li>Belegbares Interesse an MINT-Inhalten \u00fcber den regul\u00e4ren Unterricht hinaus (z.B. Betreuung entsprechender AGn, Praktika, Hobbies),<\/li>\n<li>Motivation, auch in der Freizeit an Veranstaltungen und Aktivit\u00e4ten im Rahmen von MINT teilzunehmen und<\/li>\n<li>Ausdauer, sich mindestens 2 Jahre aktiv am F\u00f6rderprogramm zu beteiligen.<\/li>\n<\/ul>\n<p><strong>\u00a0Welche Vorteile erwarten die MINToringSi-Sch\u00fcler:innen?<\/strong><\/p>\n<ul>\n<li>Intensive Kontakte innerhalb des Netzwerks zu gleichgesinnten Sch\u00fcler:innen, zu Studierenden, zur Universit\u00e4t Siegen und zu heimischen Unternehmen der Metall- und Elektro-Industrie<\/li>\n<li>Besch\u00e4ftigung mit MINT-Themen unter sachkundiger Anleitung<\/li>\n<li>Vermittlung von Schl\u00fcsselkompetenzen (etwa durch MINT-Camps und Workshops), die f\u00fcr ein (beliebiges) Studium nutzbar sind<\/li>\n<li>Bei Bedarf: Beratung und Begleitung in den ersten beiden Semestern eines MINT-Studiums an der Uni Siegen<\/li>\n<li>Erwerb von Optimierungsstrategien und Motivationsunterst\u00fctzung f\u00fcr das Studium<\/li>\n<li>Anerkennung der im Rahmen von MINToringSi erbrachten Leistungen auf dem Abiturzeugnis und ggf. Einbringen der Aktivit\u00e4ten im Rahmen einer \u201eBesonderen Lernleistung\u201c nach \u00a7 17 (APO-GOST)<\/li>\n<li><strong>NEU: Schreibworkshop zum wissenschaftlichen Schreiben zu Beginn des Programms: Die Sch\u00fcler:innen k\u00f6nnen ihre erlernten Kompetenzen in der Studien- \/ Facharbeit in der Q1 direkt anwenden!<\/strong><\/li>\n<\/ul>\n<p>Pro Schuljahr werden bis zu 30\u00a0Sch\u00fcler:innen in das Programm MINToringSi aufgenommen. Die Auswahl erfolgt durch eine Jury auf Basis einer schriftlichen Bewerbung der Sch\u00fclerin bzw. des Sch\u00fclers und einer Empfehlung durch die jeweilige Schule.<\/p>\n<p>In dem Bewerbungsschreiben sollen die letzten Noten in den naturwissenschaftlichen F\u00e4chern und Mathematik, ggf. die AG-Teilnahme in der Oberstufe und die besondere Leistung und Motivation im MINT-Bereich aufgef\u00fchrt werden. Dar\u00fcber hinaus soll der Bewerbung eine Empfehlung einer Lehrkraft beigef\u00fcgt werden. Anmeldeschluss f\u00fcr die neue Bewerbungsrunde bei MINToringSi ist der <strong>30. September 2024<\/strong>.<\/p>\n<p>Die ben\u00f6tigten Dokumente rund um die Anmeldung f\u00fcr den neuen Jahrgang gibt es nachfolgend:<br \/>\n<a href=\"http:\/\/mintoringsi.de\/wp-content\/uploads\/2024\/08\/MINToringSi-Bewerbungsleitfaden-Schueler.pdf\" target=\"_blank\" rel=\"noopener\">MINToringSi-Bewerbungsleitfaden-Sch\u00fcler<\/a><br \/>\n<a href=\"http:\/\/mintoringsi.de\/wp-content\/uploads\/2024\/08\/MINToringSi-Bewerbungsbogen.pdf\" target=\"_blank\" rel=\"noopener\">MINToringSi-Bewerbungsbogen<\/a><\/p>\n<p>Weitere Infos sind unter <a href=\"http:\/\/mintoringsi.de\/\" target=\"_blank\" rel=\"noopener\">www.mintoringsi.de<\/a>\u00a0 sowie unter <a href=\"https:\/\/nt.uni-siegen.de\/mintoringsi\/\" target=\"_blank\" rel=\"noopener\">nt.uni-siegen.de\/mintoringsi<\/a> abrufbar.<\/p>\n<p>Foto: Archivfoto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MINToringSi ist ein Kooperationsprogramm des Verbandes der Siegerl\u00e4nder Metallindustriellen (VdSM), der Universit\u00e4t Siegen und der Bezirksregierung Arnsberg. Das Ziel ist es, junge Menschen f\u00fcr die&#8230;<\/p>\n","protected":false},"author":6,"featured_media":31263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8,32,30],"tags":[],"class_list":["post-32482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausbildung","category-infos","category-vermischtes"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2023\/08\/MINT-Camp-2019-Mintor-Schellert-und-Schueler-Foto-Julia-Foerster-scaled-e1692021252850.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=32482"}],"version-history":[{"count":3,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32482\/revisions"}],"predecessor-version":[{"id":32485,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/32482\/revisions\/32485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/31263"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=32482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=32482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=32482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}