{"id":3163,"date":"2016-01-22T09:45:47","date_gmt":"2016-01-22T08:45:47","guid":{"rendered":"http:\/\/www.vdsm.net\/wronline\/?p=3163"},"modified":"2016-01-22T09:45:47","modified_gmt":"2016-01-22T08:45:47","slug":"einbussen-im-maschinenbau-trueben-die-ausfuhrbilanz","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/einbussen-im-maschinenbau-trueben-die-ausfuhrbilanz\/","title":{"rendered":"Einbu\u00dfen im Maschinenbau tr\u00fcben die Ausfuhrbilanz"},"content":{"rendered":"<p>Die Auslandsums\u00e4tze entwickelten sich in den ersten elf Monaten des vergangenen Jahres \u00fcberwiegend positiv. Gleichwohl schrumpfte das Exportvolumen der Unternehmen mit mehr als 50 Besch\u00e4ftigten gegen\u00fcber 2014 um insgesamt 2,5 Prozent. Urs\u00e4chlich hierf\u00fcr waren Einbu\u00dfen im Maschinen- und Anlagenbau. Die Exportums\u00e4tze der Metallerzeugung und -bearbeitung kletterten gegen\u00fcber dem Vorjahreszeitraum zwar um 16,7 Prozent. Mit einem Plus von 11,7 Prozent zog auch die Ausfuhr von Gummi- und Kunststoffwaren stark an. \u201eDer Maschinen- und Anlagenbau musste indessen starke Exporteinbu\u00dfen von fast 30 Prozent verkraften. Dies tr\u00fcbt die ansonsten positive Ausfuhrentwicklung und erkl\u00e4rt zugleich die r\u00fcckl\u00e4ufigen Exportums\u00e4tze&#8220;, erl\u00e4utert IHK-Gesch\u00e4ftsf\u00fchrer Rudolf K\u00f6nig gen. Kersting die Entwicklung. Der Maschinen- und Anlagenbau ist am Umsatz der Industrie mit gut 21 Prozent beteiligt und hat deshalb einen erheblichen Einfluss auf das Gesamtergebnis. Daher fiel die Ausfuhrbilanz 2015 insgesamt negativ aus. Fast zwangsl\u00e4ufig sank zugleich auch die Exportquote von 43,7 Prozent im Vorjahr auf jetzt 42,5 Prozent. Mit gut 5,3 Milliarden. Euro lag der Auslandsumsatz 2015 gleichwohl noch auf einem hohen Niveau, erreichte aber nicht mehr den Spitzenwert des Jahres 2011 (6,1 Milliarden Euro).<\/p>\n<p>Rudolf K\u00f6nig f\u00fchrt f\u00fcr die negative Exportentwicklung im Maschinen- und Anlagenbau mehrere Gr\u00fcnde auf: \u201eRusslands Nachfrage ist infolge des Rubelverfalls, der Wirtschaftskrise und der Wirtschaftssanktionen sp\u00fcrbar zur\u00fcckgegangen. Weltweit gibt es zudem \u00dcberkapazit\u00e4ten in der Stahlerzeugung. Deshalb wird deutlich weniger in neue Anlagen investiert. Zudem fehlt durch den Verfall der Rohstoffpreise f\u00fcr Gas und \u00d6l in etlichen L\u00e4ndern das Geld f\u00fcr gr\u00f6\u00dfere Investitionen.\u201c Investitionsg\u00fcter seien deshalb nur unter erheblichen Preisnachl\u00e4ssen zu verkaufen.<\/p>\n<p>W\u00e4hrend die Auslandsums\u00e4tze zur\u00fcckgingen, verkauften die Unternehmen im Inland wieder deutlich mehr Waren. Deshalb stieg der Gesamtumsatz insgesamt gegen\u00fcber dem Vorjahr leicht an und erreichte ein Volumen von 12,5 Milliarden Euro. 2008 und 2011 hatte er mit jeweils knapp 12,9 Milliarden Euro aber h\u00f6her gelegen. Ungeachtet der Exporteinbr\u00fcche im Maschinen- und Anlagenbau erreichte die Zahl der von der IHK Siegen f\u00fcr die Ausfuhr erteilten Ursprungszeugnisse mit 12.113 Urkunden einen neuen H\u00f6chststand. Die Gesamtzahl aller von der IHK ausgestellten Ausfuhrbescheinigungen betrug 40.103 und lag damit nur geringf\u00fcgig unter der Rekordzahl des Jahres 2012 (41.338).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Auslandsums\u00e4tze entwickelten sich in den ersten elf Monaten des vergangenen Jahres \u00fcberwiegend positiv. Gleichwohl schrumpfte das Exportvolumen der Unternehmen mit mehr als 50 Besch\u00e4ftigten&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":["post-3163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionale-wirtschaft"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2015\/08\/wronline-header-regionale-wirtschaftt.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/3163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=3163"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/3163\/revisions"}],"predecessor-version":[{"id":3164,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/3163\/revisions\/3164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/2675"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=3163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=3163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=3163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}