{"id":30297,"date":"2023-01-23T10:07:15","date_gmt":"2023-01-23T09:07:15","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=30297"},"modified":"2023-01-23T10:07:15","modified_gmt":"2023-01-23T09:07:15","slug":"hub45-dezentrale-arbeitsorte-zur-entlastung-der-pendlerinnen-und-pendler-sowie-zur-profilierung-suedwestfalens","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/hub45-dezentrale-arbeitsorte-zur-entlastung-der-pendlerinnen-und-pendler-sowie-zur-profilierung-suedwestfalens\/","title":{"rendered":"\u201eHub45\u201c \u2013 Dezentrale Arbeitsorte zur Entlastung der Pendlerinnen und Pendler sowie zur Profilierung S\u00fcdwestfalens"},"content":{"rendered":"<p>Die gesperrte Rahmedetalbr\u00fccke der A45 belastet die gesamte Wirtschaftsregion S\u00fcdwestfalen enorm. F\u00fcr viele Unternehmen und Verwaltungen wird es schwierig, Fachkr\u00e4fte zu halten oder neue zu gewinnen, wenn diese t\u00e4glich lange im Stau stehen m\u00fcssen. \u00dcber das Projekt \u201eHub45\u201c sollen die Betroffenen neue Perspektiven erhalten. Das Ziel: In S\u00fcdwestfalen, vor allen Dingen entlang der A45, sollen neue dezentrale Orte f\u00fcr digitales Arbeiten entstehen, die auch nach dem Br\u00fcckenneubau Bestand haben. F\u00fcr das Projekt \u201eHub45 \u2013 Neue Orte des digitalen Arbeitens\u201c \u00fcberreichte nun Mona Neubaur, Ministerin f\u00fcr Wirtschaft, Industrie, Klimaschutz und Energie des Landes Nordrhein-Westfalen einen F\u00f6rderbescheid \u00fcber 540.000 Euro.<\/p>\n<p>\u201eDie Sperrung der Br\u00fccke zwingt viele Pendlerinnen und Pendler zu deutlich l\u00e4ngeren Fahrzeiten. Gleichzeitig wollen und k\u00f6nnen viele Arbeitnehmerinnen und Arbeitnehmer aber nicht dauerhaft im Home-Office arbeiten. Das Projekt Hub45 kann einen wichtigen Beitrag dazu leisten, die dringend ben\u00f6tigten Fachkr\u00e4fte in S\u00fcdwestfalen zu halten, bis die neue Br\u00fccke steht\u201c, sagte NRW-Wirtschaftsministerin Mona Neubaur. \u201eEs ist ein wichtiger erg\u00e4nzender Baustein zu den bereits von der Landesregierung ergriffenen Unterst\u00fctzungsma\u00dfnahmen wie der Einrichtung des \u201eNRW.BANK.Universalkredit A 45\u201c und der Erweiterung der F\u00f6rdergebietskulisse des Regionalen Wirtschaftsf\u00f6rderungsprogramms um den M\u00e4rkischen Kreis und den Hochsauerlandkreis.\u201c<\/p>\n<p>Die F\u00f6rderung des Landes bel\u00e4uft sich auf drei Jahre. Angesiedelt und koordiniert wird \u201eHub45\u201c bei der S\u00fcdwestfalen Agentur GmbH. Die anderthalb Stellen f\u00fcr das Projektmanagement sind ab sofort ausgeschrieben.<\/p>\n<p>Hinter dem englischen Begriff \u201eHub\u201c verbirgt sich ein Knotenpunkt. \u201eHub45\u201c will daf\u00fcr sorgen, dass in S\u00fcdwestfalen ein ganzes Netz solcher Knotenpunkte entsteht. In einem ersten Schritt geht es um Pendlerstrecken entlang der A45. \u201ePriorit\u00e4t hat nat\u00fcrlich f\u00fcr uns der schnelle Neubau der Br\u00fccke. Parallel m\u00fcssen wir aber die richtigen Weichen f\u00fcr unsere Zukunft als Wirtschaftsstandort stellen, um unsere Unternehmen und Verwaltungen jetzt zu unterst\u00fctzen\u201c, sagte Marco Voge, Landrat des M\u00e4rkischen Kreises, bei der F\u00f6rderbescheid-\u00dcbergabe. \u201eDie Idee dezentraler Arbeitsorte trifft den Nerv der Unternehmen und ist gleichzeitig eine Investition in die zuk\u00fcnftige Standortattraktivit\u00e4t\u201c, erg\u00e4nzte Maik Rosenberg, Vorsitzender des Vereins \u201eWirtschaft f\u00fcr S\u00fcdwestfalen\u201c, dem fast 400 Unternehmen angeh\u00f6ren.<\/p>\n<p>Dem Projektantrag vorausgegangen war eine Befragung bei Unternehmen und Verwaltungen in der Region \u2013 gemeinsam mit Industrie- und Handelskammern aus S\u00fcdwestfalen sowie dem M\u00e4rkischen Arbeitgeberverband. Die Ergebnisse hatten die Bedarfe f\u00fcr digitales, wohnortnahes Lernen und Arbeiten bekr\u00e4ftigt. Sie zeigten aber auch, dass einige Institutionen noch nicht selbst aktiv geworden sind. \u201eDas \u201aHub45\u2018 baut und finanziert diese neuen Orte nicht. Wir schaffen eine zentrale Anlaufstelle, die Bedarfe und Akteurinnen und Akteure zusammenbringt, bestehende Coworking-Spaces und neue Angebote vernetzt und Hilfestellung geben kann beim Aufbau innovativer Orte\u201c, erl\u00e4uterte Sebastian Yun Christmann, Projektmanager bei der REGIONALE 2025 in der S\u00fcdwestfalen Agentur, der den Projektantrag vorbereitet hatte.<\/p>\n<p>\u201eDas Projekt \u201eHub45 \u2013 Neue Orte des digitalen Arbeitens\u201c erg\u00e4nzt ausgezeichnet die Projektentwicklungen im Bereich modernen, digitalen Arbeitens, die sich schon in der REGIONALE 2025 ergeben. So besch\u00e4ftigen sich beispielsweise die Sauerland-Seen mit Themen wie Coworkation und Kommunen wie Halver mit neuen Quartieren f\u00fcr Wohnen und Arbeiten\u201c, ordnete Hubertus Winterberg, Gesch\u00e4ftsf\u00fchrer der S\u00fcdwestfalen Agentur GmbH, das Vorhaben ein.<\/p>\n<p><em>Zu den regionalen Unterst\u00fctzern des Vorhabens z\u00e4hlen die Wirtschaftsf\u00f6rderungen aller f\u00fcnf Kreise, die Industrie- und Handelskammern Arnsberg, Hagen und Siegen, der M\u00e4rkische Arbeitgeberverband, der Deutsche Gewerkschaftsbund Region S\u00fcdwestfalen sowie der Sauerland Tourismus. Ihre Erfahrung als Entwicklungspartner im Projekt bringen dar\u00fcber hinaus CoWorkLand aus Kiel, Netzwerk Zukunftsorte aus Brandenburg und Mia Engadina aus der Schweiz ein.<\/em><em><br \/>\n<\/em><\/p>\n<p>Text:\u00a0<a href=\"https:\/\/www.suedwestfalen-agentur.com\/\" target=\"_blank\" rel=\"noopener\">S\u00fcdwestfalen Agentur<\/a>; Foto: MWIKE NRW<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die gesperrte Rahmedetalbr\u00fccke der A45 belastet die gesamte Wirtschaftsregion S\u00fcdwestfalen enorm. F\u00fcr viele Unternehmen und Verwaltungen wird es schwierig, Fachkr\u00e4fte zu halten oder neue zu&#8230;<\/p>\n","protected":false},"author":6,"featured_media":30298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[32,30,11],"tags":[],"class_list":["post-30297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos","category-vermischtes","category-regionale-wirtschaft"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2023\/01\/Hub45_Foto_MWIKE_NRW_WEB.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/30297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=30297"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/30297\/revisions"}],"predecessor-version":[{"id":30299,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/30297\/revisions\/30299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/30298"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=30297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=30297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=30297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}