{"id":30057,"date":"2022-11-30T09:10:27","date_gmt":"2022-11-30T08:10:27","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=30057"},"modified":"2022-12-19T15:39:39","modified_gmt":"2022-12-19T14:39:39","slug":"mennekes-errichtet-neues-verwaltungsgebaeude","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/mennekes-errichtet-neues-verwaltungsgebaeude\/","title":{"rendered":"MENNEKES errichtet neues Verwaltungsgeb\u00e4ude"},"content":{"rendered":"<p>Bei der MENNEKES Gruppe rollen wieder die Bagger: Am Standort Kirchhundem-Welschen Ennest errichtet der Elektrotechnik-Spezialist ein neues Geb\u00e4ude f\u00fcr die Verwaltung. Gebaut wird seit Kurzem, die Fertigstellung ist f\u00fcr das Fr\u00fchjahr 2024 geplant. Die Gesamtbaukosten belaufen sich auf rund 7 Millionen Euro. 110 neue B\u00fcroarbeitspl\u00e4tze werden geschaffen.<\/p>\n<p>An der K\u00f6lner Stra\u00dfe, wo MENNEKES schon seit 2013 sein Logistikzentrum hat und wo bereits 2019 zwei moderne Verwaltungsgeb\u00e4ude inklusive Kundenzentrum und Cafeteria entstanden, wird nun Geb\u00e4ude Nummer Drei gebaut. \u201eM10.3.\u201c komplettiert die bisherigen beiden Verwaltungsgeb\u00e4ude \u201eM10.1\u201c und \u201eM10.2\u201c. Das neue Geb\u00e4ude umfasst drei Stockwerke plus Keller und ist 2.500 Quadratmeter gro\u00df.<\/p>\n<p>Bei der Errichtung von \u201eM10.3\u201c liegt ein besonderer Schwerpunkt auf dem nachhaltigen, also ressourcen- und umweltschonenden Bauen nach den Kriterien der Deutschen Gesellschaft f\u00fcr nachhaltiges Bauen (DGNB). Der Bau erfolgt in Holz-Beton-Verbundbauweise und alle eingesetzten Baustoffe werden entsprechend der DGNB-Vorgaben gepr\u00fcft \u2013 sodass mit der Bauma\u00dfnahme ein m\u00f6glichst geringer CO2-Fu\u00dfabdruck hinterlassen wird und im fertigen Geb\u00e4ude \u00fcber Jahrzehnte ein gesundes Raumklima herrschen kann.<\/p>\n<p>Ebenfalls von Beginn an auf Nachhaltigkeit ausgerichtet ist das Energiemanagement des Geb\u00e4udes: Wie die bisherigen Verwaltungsgeb\u00e4ude in Welschen Ennest so soll auch das neue Geb\u00e4ude mit der Abw\u00e4rme, die im nahegelegenen Produktionsgeb\u00e4ude entsteht, geheizt werden. M\u00f6glich macht das ein ausgekl\u00fcgeltes System mit zwei gro\u00dfen unterirdischen Wasserspeichern und einem Nahw\u00e4rmenetz. Themen wie Barrierefreiheit und variable Nutzung werden beim Bau des Geb\u00e4udes ebenfalls entsprechend ber\u00fccksichtigt.<\/p>\n<p>Mit dem neuen Verwaltungsgeb\u00e4ude schafft MENNEKES weitere B\u00fcror\u00e4ume f\u00fcr die Mitarbeiterinnen und Mitarbeiter seines Gesch\u00e4ftsbereichs Elektromobilit\u00e4t sowie seiner Zentralen Serviceabteilungen. In den bisherigen Verwaltungsgeb\u00e4uden in Welschen Ennest sind unter anderem bereits die IT-Abteilung und die MENNEKES Stecker GmbH und Co. KG untergebracht, die als Teil der Unternehmensgruppe f\u00fcr die Automobilindustrie spezifische Ladekabel und Lade-Inlets \u2013 die Steckdosen hinter den Tankklappen von E-Fahrzeugen \u2013 entwickelt und produziert.<\/p>\n<p>Christopher Mennekes, gesch\u00e4ftsf\u00fchrender Gesellschafter von MENNEKES, zum Bauvorhaben: \u201eDank unseres soliden Industriegesch\u00e4fts, des Wachstums des eMobility-Marktes und vorausschauendem Wirtschaften geht es unserem Unternehmen trotz der aktuellen Herausforderungen und weltweiten Krisen gut. Wir sind daher in der komfortablen Situation, unseren Standort in Welschen Ennest weiter vergr\u00f6\u00dfern zu k\u00f6nnen und legen dabei bewusst einen starken Fokus auf das Thema nachhaltiges Bauen.\u201c<\/p>\n<p>Geplant und geleitet wird das Bauvorhaben von der Stoppacher Ingenieurgesellschaft, mit der MENNEKES bereits seit vielen Jahren vertrauensvoll zusammenarbeitet.<\/p>\n<p>Text:\u00a0<a href=\"https:\/\/www.mennekes.de\/\" target=\"_blank\" rel=\"noopener\">MENNEKES Elektrotechnik GmbH &amp; Co. KG<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei der MENNEKES Gruppe rollen wieder die Bagger: Am Standort Kirchhundem-Welschen Ennest errichtet der Elektrotechnik-Spezialist ein neues Geb\u00e4ude f\u00fcr die Verwaltung. Gebaut wird seit Kurzem,&#8230;<\/p>\n","protected":false},"author":6,"featured_media":30059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,32,30,10],"tags":[162,161,160,159,64,70],"class_list":["post-30057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-infos","category-vermischtes","category-unternehmen","tag-baumassnahme","tag-gebaeude","tag-kirchhundem","tag-mennekes","tag-standort","tag-verwaltung"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2022\/11\/grafik_neues_verwaltungsgebaeude_WEB.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/30057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=30057"}],"version-history":[{"count":3,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/30057\/revisions"}],"predecessor-version":[{"id":30133,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/30057\/revisions\/30133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/30059"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=30057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=30057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=30057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}