{"id":28608,"date":"2022-05-18T08:59:43","date_gmt":"2022-05-18T06:59:43","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=28608"},"modified":"2022-05-18T09:01:29","modified_gmt":"2022-05-18T07:01:29","slug":"online-sprechtag-kuenstliche-intelligenz-effektiv-in-der-produktion-einsetzen","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/online-sprechtag-kuenstliche-intelligenz-effektiv-in-der-produktion-einsetzen\/","title":{"rendered":"Online-Sprechtag: K\u00fcnstliche Intelligenz effektiv in der Produktion einsetzen"},"content":{"rendered":"<p>Sie ist \u00fcberall, die vielzitierte Digitalisierung: Kontaktlos beim B\u00e4cker um die Ecke bezahlen, den Elternsprechtag digital per Videokonferenz abhalten und mit der Online-Ausweisfunktion das neue Auto von zu Hause aus anmelden. Unser Alltag ist in den letzten Jahren rasant digitalisiert worden \u2013 trotzdem werden viele Potenziale noch nicht ausgesch\u00f6pft.<\/p>\n<p>Um gezielt Unternehmen beim Thema Digitalisierung und F\u00f6rderung zu unterst\u00fctzen, hat sich das Mittelstand 4.0-Kompetenzzentrum Siegen mit der Besch\u00e4ftigungsf\u00f6rderung des Kreises Siegen-Wittgenstein zusammengeschlossen. W\u00e4hrend das Kompetenzzentrum kleine und mittlere Unternehmen in S\u00fcdwestfalen in allen Fragen und Problemen rund um das Thema Digitalisierung unterst\u00fctzt, ber\u00e4t die Regiestelle des Kreises Siegen-Wittgenstein zu passenden F\u00f6rderprogrammen f\u00fcr Digitalisierungsvorhaben und hilft bei der Antragstellung.<\/p>\n<p>Aus dieser Kooperation ist die Veranstaltungsreihe \u201eInnovationswerkstatt 2.0 \u2013 Online-Sprechtag zu Digitalisierung und F\u00f6rderm\u00f6glichkeiten\u201c entstanden. Von der digitalen Produktion bis hin zur Gesch\u00e4ftsmodellentwicklung k\u00f6nnen sich Unternehmen \u00fcber verschiedene Themenschwerpunkte informieren und vor allem ihre eigenen Fragen und Anliegen einbringen.<\/p>\n<p>Der n\u00e4chste Online-Termin findet statt am Dienstag, 24. Mai 2022, zu dem Thema \u201eKI in der Produktion\u201c. In der Zeit von 10:00 bis 15:00 Uhr k\u00f6nnen kleine und mittlere Unternehmen bis maximal 500 Mitarbeiterinnen und Mitarbeitern an den Einzelsprechstunden teilnehmen.<\/p>\n<p>Tobias Schmelter, KI-Trainer, beantwortet Fragen zu Einsatzpotenzialen von K\u00fcnstlicher Intelligenz (KI) in Produktionssystemen, Prozessintegration und -analyse auf Basis von KI sowie zu Datenakquise-, nutzung und -verarbeitung. Josefine Zilke, Ansprechpartnerin des Kreises Siegen-Wittgenstein f\u00fcr F\u00f6rderprogramme im Bereich Digitalisierung, gibt Tipps, wie Unternehmen das passende F\u00f6rderprogramm finden und einen entsprechenden Antrag stellen k\u00f6nnen.<\/p>\n<p>Die Innovationswerkstatt 2.0 findet einmal im Monat zu jeweils wechselnden Themen statt. Kleine und mittlere Unternehmen k\u00f6nnen sich f\u00fcr einst\u00fcndige Einzelsprechstunden anmelden und gemeinsam mit den Expertinnen und Experten des Kompetenzzentrums und der Besch\u00e4ftigungsf\u00f6rderung ihre Digitalisierungsvorhaben und entsprechende F\u00f6rderm\u00f6glichkeiten besprechen. \u201eGanz egal, ob sich die Unternehmen allgemein informieren m\u00f6chten oder schon konkrete Ideen haben, ob sie bereits Erfahrungen gesammelt haben oder noch ganz am Anfang stehen \u2013 wir geben die n\u00f6tigen Informationen und kl\u00e4ren individuelle Fragen\u201c, erkl\u00e4rt Zilke.<\/p>\n<p>Die Teilnahme an den Online-Sprechstunden ist kostenfrei. Interessierte Unternehmen k\u00f6nnen sich \u00fcber die Website des Mittelstand 4.0-Kompetenzzentrums anmelden und dort weitere Informationen erhalten: <a href=\"http:\/\/www.kompetenzzentrum-siegen.digital\" target=\"_blank\" rel=\"noopener\">www.kompetenzzentrum-siegen.digital<\/a>.<\/p>\n<p>Das neue Angebot des Kompetenzzentrums und des Kreises Siegen-Wittgenstein wird durch die IHK Siegen, Handwerkskammer S\u00fcdwestfalen, Kreishandwerkerschaft Westfalen S\u00fcd, Arbeitgeberverb\u00e4nde Siegen-Wittgenstein und ZDW S\u00fcdwestfalen GmbH unterst\u00fctzt.<\/p>\n<p>Fragen beantworten Josefine Zilke, 0271 333 1145 \/ <a href=\"mailto:j.zilke@siegen-wittgenstein.de\">j.zilke@siegen-wittgenstein.de<\/a> und Jennifer Novak, 0271 7403289 \/ <a href=\"mailto:novak@kompetenzzentrum-siegen.digital\">novak@kompetenzzentrum-siegen.digital<\/a>.<\/p>\n<p>Text: <a href=\"http:\/\/www.siegen-wittgenstein.de\" target=\"_blank\" rel=\"noopener\">Kreis Siegen-Wittgenstein<\/a>; Foto:\u00a0Mittelstand 4.0 Kompetenzzentrum Siegen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie ist \u00fcberall, die vielzitierte Digitalisierung: Kontaktlos beim B\u00e4cker um die Ecke bezahlen, den Elternsprechtag digital per Videokonferenz abhalten und mit der Online-Ausweisfunktion das neue&#8230;<\/p>\n","protected":false},"author":6,"featured_media":28609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,32,30,34],"tags":[],"class_list":["post-28608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-infos","category-vermischtes","category-termine"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2022\/05\/vernetzte-Produktion-WEB.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/28608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=28608"}],"version-history":[{"count":1,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/28608\/revisions"}],"predecessor-version":[{"id":28610,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/28608\/revisions\/28610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/28609"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=28608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=28608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=28608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}