{"id":22942,"date":"2021-03-29T08:26:33","date_gmt":"2021-03-29T06:26:33","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=22942"},"modified":"2021-03-29T08:26:33","modified_gmt":"2021-03-29T06:26:33","slug":"attendorner-medizin-gespraeche-gehen-in-die-2-runde","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/attendorner-medizin-gespraeche-gehen-in-die-2-runde\/","title":{"rendered":"Attendorner Medizin-Gespr\u00e4che gehen in die 2. Runde"},"content":{"rendered":"<p>Am kommenden Mittwoch, den 31. M\u00e4rz 2021 um 17 Uhr, geht die digitale Vortragsreihe \u201eAttendorner Medizin Gespr\u00e4che\u201c der Helios Klinik Attendorn mit dem Vortrag \u201eGut zu Fu\u00df \u2013 Ursachen und Therapien bei Fu\u00dfdeformit\u00e4ten\u201c in die zweite Runde.<\/p>\n<p>Unsere F\u00fc\u00dfe tragen uns ein Leben lang und nehmen jeden Tag beeindruckende Belastungen auf sich. Obwohl man sie in der Regel nicht sieht, da sie den \u00fcberwiegenden Tag in mehr oder weniger gutem Schuhwerk stecken, tragen sie uns doch zuverl\u00e4ssig durch den Alltag und werden den individuellen Anforderungen im Beruf, Freizeit und auch im Hinblick auf das K\u00f6rpergewicht gerecht. Dennoch leiden viele Menschen unter erheblichen Beschwerden ihrer F\u00fc\u00dfe mit daraus resultierenden Bewegungseinschr\u00e4nkungen und Schmerzen. Hierf\u00fcr k\u00f6nnen angeborene Fehlstellungen, \u00dcberlastungssyndrome und Verschlei\u00df verantwortlich sein.<\/p>\n<p>In seinem Vortrag thematisiert Dr. Manfred Kemmerling, Chefarzt der Abteilung f\u00fcr Orthop\u00e4die, Rheumatologie und Traumatologie die moderne Fu\u00dfchirurgie. Veranschaulicht werden verschiedene Ursachen von Fu\u00dfbeschwerden sowie M\u00f6glichkeiten der konservativen, d. h. nicht operativen Behandlung, wie Physiotherapie und Krankengymnastik. Eine Vielzahl von Fu\u00dfdeformit\u00e4ten und Fehlstellungen bed\u00fcrfen jedoch einer operativen Therapie und Korrektur, um ein schmerz- und beschwerdefreies Gehen wieder zu erm\u00f6glichen. Dabei stehen moderne gelenkerhaltene Techniken im Vordergrund der operativen Therapie, die auf die individuellen Bed\u00fcrfnisse und Deformit\u00e4ten des Patienten abgestimmt und im Vortrag vorgestellt und erl\u00e4utert werden. Wie bei Pr\u00e4senzvortr\u00e4gen k\u00f6nnen selbstverst\u00e4ndlich auch online im Anschluss Fragen gestellt werden.<\/p>\n<p>Alle Interessierten ben\u00f6tigen lediglich ein Endger\u00e4t (zum Beispiel einen Laptop oder ein Tablet). \u00dcber einen Zugangslink auf der Homepage gelangen Sie automatisch zu unserem Skype-Vortrag. Die Teilnehmerzahl ist unbegrenzt und eine vorherige Anmeldung ist nicht n\u00f6tig. Alle Informationen zum Programm und Zugang finden Sie unter <a href=\"https:\/\/www.helios-gesundheit.de\/attendorn\" target=\"_blank\" rel=\"noopener\">www.helios-gesundheit.de\/attendorn<\/a>.<\/p>\n<p>Bild und Info: <a href=\"https:\/\/www.helios-gesundheit.de\/kliniken\/attendorn\/\" target=\"_blank\" rel=\"noopener\">Helios Klinik Attendorn<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am kommenden Mittwoch, den 31. M\u00e4rz 2021 um 17 Uhr, geht die digitale Vortragsreihe \u201eAttendorner Medizin Gespr\u00e4che\u201c der Helios Klinik Attendorn mit dem Vortrag \u201eGut&#8230;<\/p>\n","protected":false},"author":2,"featured_media":22355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,34,10],"tags":[],"class_list":["post-22942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos","category-termine","category-unternehmen"],"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2021\/02\/Arzt_Pflege_Gruppe.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/22942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=22942"}],"version-history":[{"count":2,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/22942\/revisions"}],"predecessor-version":[{"id":22944,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/22942\/revisions\/22944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/22355"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=22942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=22942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=22942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}