{"id":22159,"date":"2021-02-05T19:53:00","date_gmt":"2021-02-05T18:53:00","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=22159"},"modified":"2021-02-05T19:53:08","modified_gmt":"2021-02-05T18:53:08","slug":"ovg-urteil-herber-rueckschlag-fuer-route-57","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/ovg-urteil-herber-rueckschlag-fuer-route-57\/","title":{"rendered":"OVG-Urteil \u201eherber R\u00fcckschlag f\u00fcr Route 57\u201c"},"content":{"rendered":"<p>\u201eDas Urteil ist ein herber R\u00fcckschlag &#8211; nicht nur f\u00fcr die Stadt Kreuztal. Das f\u00fcr die Menschen in der Region wichtige Aufbruchssignal ist ausgeblieben. Mit der S\u00fcdumgehung m\u00fcssen sie nun auch auf den baulichen Einstieg in die Ortsumgehungskette Route 57 weiter warten. Abermals zeigt sich eindrucksvoll, wie wichtige Infrastrukturprojekte sich immer wieder verz\u00f6gern. Absurdistan l\u00e4sst gr\u00fc\u00dfen!\u201c Christian F. Kocherscheidt, Vizepr\u00e4sident der IHK Siegen, bedauert den Beschluss des Oberverwaltungsgerichts NRW zur Klage eines Reitvereins gegen den schon vor drei Jahren offengelegten Planfeststellungsbeschluss zur Teilortsumgehung Kreuztal. \u201eDer Richterspruch ist f\u00fcr uns entt\u00e4uschend. Wir h\u00e4tten uns ein anderes Signal gew\u00fcnscht. Immerhin k\u00e4mpft die Region seit Jahrzehnten daf\u00fcr, dass Wittgenstein und das Siegerland verkehrlich besser miteinander verbunden werden!\u201c Es sei frustrierend zu sehen, wie die Umsetzung demokratisch gefasster Mehrheitsbeschl\u00fcsse zur Route 57 auf Ebene der Gemeinden, des Kreises, des Landes und des Bundes immer wieder ausgebremst werde. Kocherscheidt erinnert daran, dass sich die Region auf allen Ebenen Schulter an Schulter f\u00fcr die Ortsumgehungskette eingesetzt hatte.<\/p>\n<p>Es wird demnach weiter dauern, bis die Umgehungsstra\u00dfe in Bau gehen kann und sich eine verkehrliche Entlastung f\u00fcr die Stadt Kreuztal einstellt. Ulf P\u00f6ppel, Gesch\u00e4ftsf\u00fchrer der REGUPOL BSW GmbH in Bad Berleburg, l\u00e4sst die Hoffnung dennoch nicht ganz fahren: \u201eWir hoffen weiter auf die dringend ben\u00f6tigte Ortsumgehung. Aber sie ist am Ende nur ein Teil dessen, was wir uns seit Jahrzehnten w\u00fcnschen. Wir brauchen die Route 57, weil sie uns am Ende n\u00e4her zu unseren Kunden bringt und unserem Unternehmen sowie den Mitarbeiterinnen und Mitarbeitern unmittelbar hilft.\u201c Fachkr\u00e4fte h\u00e4tten heute klare Erwartungen in puncto Erreichbarkeit des Arbeitsplatzes. Wo fr\u00fcher l\u00e4ngere Arbeitswege unter Umst\u00e4nden noch akzeptiert worden seien, sto\u00dfe dies mittlerweile nur noch auf Unverst\u00e4ndnis. Ulf P\u00f6ppel: \u201eF\u00fcr junge Menschen hat Mobilit\u00e4t einen gewaltigen Stellenwert, viele sehen sie als eine Art Grundrecht. Dabei geht es nicht nur um Entfernungen und Zeitersparnisse, sondern vor allem um ein stressfreies Ankommen am Arbeitsplatz!\u201c<\/p>\n<p>\u00c4hnlich bewertet auch Eckehard Hof die Bedeutung des Verkehrsprojektes. Der Gesch\u00e4ftsf\u00fchrer der BERGE-BAU GmbH &amp; Co. KG in Leimstruth (Erndtebr\u00fcck) engagiert sich seit vielen Jahren gemeinsam mit anderen Akteuren im Verein Route 57, der sich f\u00fcr die Ortsumgehungskette starkmacht. \u201eJeder Kilometer Ortsumgehung, der nicht entsteht, schw\u00e4cht unsere unternehmerische Wettbewerbssituation und damit den Wohn- und Arbeitsstandort Wittgenstein.\u201c Wer seinen Firmensitz in Wittgenstein habe, m\u00fcsse ohnehin schon mit langen Anfahrtsrouten leben. \u201eAber zeitraubende Staus und Unf\u00e4lle sorgen f\u00fcr einen erheblichen Wettbewerbsnachteil. W\u00e4hrend andere schon beim Kunden sind, befinden wir uns noch nicht mal auf der Autobahn. Deshalb ist die Nachricht \u00fcber das aktuelle OVG-Urteil f\u00fcr uns und die gesamte Region immens entt\u00e4uschend und entmutigend!\u201c, betont der Gesch\u00e4ftsf\u00fchrer.<\/p>\n<p>Mit dem Gerichtsurteil setze sich die \u201ebeispiellose planerische Endlosgeschichte\u201c fort, unterstreicht Christian F. Kocherscheidt. Immerhin habe die Linienbestimmung f\u00fcr die S\u00fcdumgehung bereits 1993 stattgefunden. 2008 war der Vorentwurf genehmigt worden. Der Planfeststellungsbeschluss wurde nach etlichen Verz\u00f6gerungen Ende 2017 gefasst und Anfang 2018 ver\u00f6ffentlicht. Seitdem stand die Klage des Reitbetriebes im Raum. \u201eDass drei Jahre f\u00fcr eine Entscheidung nicht ausreichen und es nun zu neuen Verz\u00f6gerungen kommt, ist absurd. Man kommt sich vor wie bei \u201aVerstehen Sie Spa\u00df?\u2018, nur dass schon lange nicht mehr zum Lachen zumute ist!\u201c<\/p>\n<p>Info: <a href=\"https:\/\/www.ihk-siegen.de\/\" target=\"_blank\" rel=\"noopener\">IHK Siegen<\/a><\/p>\n<p><strong>Zum Hintergrund:<\/strong><\/p>\n<p>Das Oberverwaltungsgericht M\u00fcnster hat am Freitag den Planfeststellungsbeschluss f\u00fcr die Kreuztaler S\u00fcdumgehen\u00a0\u00a0f\u00fcr rechtswidrig und nicht vollziehbar erkl\u00e4rt. Die Stra\u00dfe darf damit vorerst nicht gebaut werden. Den weitergehenden Antrag des klagenden Reit- und Fahrvereins Kindelsberg auf Aufhebung des Planfeststellungsbeschlusses hat es dagegen abgewiesen.<\/p>\n<p>Die Richter begr\u00fcnden ihr Urteil damit, dass die Abw\u00e4gung des beklagten Landes NRW fehlerhaft sei, &#8222;was die Festsetzung von naturschutzrechtlichen Ausgleichsma\u00dfnahmen auf den Grundst\u00fccken&#8220; des Vereins Kl\u00e4gers angehe. &#8222;Das Land habe die Eigent\u00fcmerstellung des Kl\u00e4gers nicht hinreichend ber\u00fccksichtigt und sich stattdessen in unzul\u00e4ssiger Weise bei der Fl\u00e4chenauswahl nur von naturschutzfachlichen Erw\u00e4gungen leiten lassen. Es sei nicht ausreichend gepr\u00fcft worden, ob naturschutzrechtliche Ma\u00dfnahmen auch in einiger Entfernung zu der geplanten Trasse h\u00e4tten realisiert werden k\u00f6nnen, damit Grundst\u00fccke des Kl\u00e4gers daf\u00fcr nicht in Anspruch genommen werden m\u00fcssten.&#8220;<\/p>\n<p>Quelle: Siegener Zeitung<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eDas Urteil ist ein herber R\u00fcckschlag &#8211; nicht nur f\u00fcr die Stadt Kreuztal. Das f\u00fcr die Menschen in der Region wichtige Aufbruchssignal ist ausgeblieben. Mit&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,32,30,11],"tags":[],"class_list":["post-22159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-infos","category-vermischtes","category-regionale-wirtschaft"],"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2016\/04\/wronline-route57.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/22159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=22159"}],"version-history":[{"count":2,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/22159\/revisions"}],"predecessor-version":[{"id":22161,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/22159\/revisions\/22161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/3595"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=22159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=22159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=22159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}