{"id":17702,"date":"2020-02-26T11:48:04","date_gmt":"2020-02-26T10:48:04","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=17702"},"modified":"2020-02-26T11:48:04","modified_gmt":"2020-02-26T10:48:04","slug":"verzoegerung-bei-der-campussanierung","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/verzoegerung-bei-der-campussanierung\/","title":{"rendered":"Verz\u00f6gerung bei der Campussanierung"},"content":{"rendered":"<p>Ein wenig m\u00fcssen sich Studierende und Universit\u00e4ts-MitarbeiterInnen noch gedulden, bevor sie die sanierte Mensa und Caf\u00e9teria, die komplett erneuerte Universit\u00e4tsbibliothek sowie die B\u00fcros und Seminarr\u00e4ume in den Geb\u00e4uden AR-H und -K wieder nutzen k\u00f6nnen: Der Abschluss des Modernisierungsprojektes auf dem Campus Adolf-Reichwein-Stra\u00dfe der Uni Siegen verz\u00f6gert sich um einige Monate. Bis zur zweiten Jahresh\u00e4lfte 2020 sollen aber alle vier Geb\u00e4udeteile fertiggestellt und betriebsbereit sein. Der urspr\u00fcngliche Zeitplan hatte eine gestaffelte Fertigstellung Ende 2019\/ Anfang 2020 vorgesehen. Die Campussanierung erfolgt im Rahmen des Hochschulbaukonsolidierungsprogramms (HKoP) und ist eines der gr\u00f6\u00dften Modernisierungsprojekte an Hochschulen in NRW.<\/p>\n<p>\u201eBei Vorhaben dieser Gr\u00f6\u00dfenordnung und Komplexit\u00e4t lassen sich Verz\u00f6gerungen leider nicht immer vermeiden. Die Zusammenarbeit zwischen BLB, Universit\u00e4t und der Baufirma Z\u00fcblin funktioniert jedoch sehr gut, das Projekt befindet sich auf der Zielgeraden. Gemeinsam setzen wir alles daran, es nun z\u00fcgig und erfolgreich abzuschlie\u00dfen\u201c, sagt Isabelle Wortmann, die zust\u00e4ndige Projektleiterin beim Bau- und Liegenschaftsbetrieb (BLB) NRW. Das vorgesehene Budget werde nach wie vor eingehalten.<\/p>\n<div id=\"attachment_17705\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2020\/02\/HKOP_Medien-2_WEB.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-17705\" class=\"size-medium wp-image-17705\" src=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2020\/02\/HKOP_Medien-2_WEB-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2020\/02\/HKOP_Medien-2_WEB-300x200.jpg 300w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2020\/02\/HKOP_Medien-2_WEB-768x512.jpg 768w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2020\/02\/HKOP_Medien-2_WEB.jpg 777w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-17705\" class=\"wp-caption-text\">Auch wenn die B\u00f6den noch abgeklebt sind, l\u00e4sst sich schon erahnen, wie es in der UB k\u00fcnftig aussieht: Hell und freundlich soll die &#8222;neue&#8220; Bibliothek werden, zum Arbeiten gibt es neben Gruppen- auch Einzelr\u00e4ume, wie hier rechts zu sehen.<\/p><\/div>\n<p>\u201eEine Sanierung im Bestand auf einer Gesamtfl\u00e4che von 100 bis 150 Einfamilienh\u00e4usern ist hochkomplex: S\u00e4mtliche Arbeitsschritte m\u00fcssen fein getaktet und aufeinander abgestimmt werden, jederzeit kann es zu unvorhergesehenen Situationen kommen\u201c, erkl\u00e4rt Uni-Kanzler Ulf Richter. So hatte sich beispielsweise die Schadstoffsanierung der Geb\u00e4udeteile als deutlich umfangreicher und zeitaufwendiger herausgestellt, als urspr\u00fcnglich angenommen. Im Bereich der Mensa erwies sich au\u00dferdem eine Zwischendecke als so marode, dass sie teilweise abgerissen und neu gebaut werden musste. Insbesondere beim Innenausbau gilt es, zahlreiche Gewerke untereinander zu koordinieren. Aufgrund der extremen Auslastung im Baugewerbe kommt es auch hier leicht zu Verz\u00f6gerungen, die sich dann auf die weiteren Schritte auswirken.<\/p>\n<p>Bis der \u201eneue\u201c Campus vollst\u00e4ndig fertig ist, bleibt auf dem Adolf-Reichwein-Campus die gewohnte \u00dcbergangsl\u00f6sung bestehen: Die Mietvertr\u00e4ge f\u00fcr die Modulbauten der Interimsmensa und -Caf\u00e9teria werden entsprechend verl\u00e4ngert, als B\u00fcro- und Seminarzentrum steht bis zum Abschluss der Ma\u00dfnahme weiterhin die Haardter-Berg-Schule zur Verf\u00fcgung. Auch die Interimsstandorte der Universit\u00e4tsbibliothek bleiben bestehen, bis der Umzug der B\u00fccher in die sanierte Bibliothek abgeschlossen ist.<\/p>\n<p>Text und Fotos: <a href=\"http:\/\/www.uni-siegen.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Uni Siegen<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein wenig m\u00fcssen sich Studierende und Universit\u00e4ts-MitarbeiterInnen noch gedulden, bevor sie die sanierte Mensa und Caf\u00e9teria, die komplett erneuerte Universit\u00e4tsbibliothek sowie die B\u00fcros und Seminarr\u00e4ume&#8230;<\/p>\n","protected":false},"author":6,"featured_media":17704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8,32,30],"tags":[],"class_list":["post-17702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausbildung","category-infos","category-vermischtes"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2020\/02\/HKOP_Medien-1_WEB.jpg","_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/17702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=17702"}],"version-history":[{"count":2,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/17702\/revisions"}],"predecessor-version":[{"id":17706,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/17702\/revisions\/17706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/17704"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=17702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=17702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=17702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}