{"id":15690,"date":"2019-09-13T11:48:42","date_gmt":"2019-09-13T09:48:42","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=15690"},"modified":"2019-09-13T11:49:17","modified_gmt":"2019-09-13T09:49:17","slug":"nachhaltige-logistikkonzepte-fuer-den-guetertransport-sind-gefragt","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/nachhaltige-logistikkonzepte-fuer-den-guetertransport-sind-gefragt\/","title":{"rendered":"Nachhaltige Logistikkonzepte f\u00fcr den G\u00fctertransport gefragt"},"content":{"rendered":"<p>Die s\u00fcdwestf\u00e4lische Wirtschaft ist auf effiziente und zuverl\u00e4ssige Verkehrsanbindungen angewiesen. Vor dem Hintergrund einer Zunahme des G\u00fcterverkehrsaufkommen und langfristigen Br\u00fcckenbauarbeiten auf den Bundesautobahnen A4 und A45 sind alle am Transport und der Logistikplanung Beteiligten interessiert, den Anteil der Eisenbahn im Mix der Verkehrstr\u00e4ger zur Entlastung der Stra\u00dfen in S\u00fcdwestfalen auszuweiten. Hendrik W\u00fcst, Verkehrsminister des Landes Nordrhein-Westfalen, hob in seiner Begr\u00fc\u00dfung die Bedeutung intermodaler Ans\u00e4tze f\u00fcr die Mobilit\u00e4t der Zukunft hervor. Welche Rolle \u00fcbernimmt in diesem Zusammenhang das k\u00fcrzlich in Betrieb genommene Container Terminal-S\u00fcdwestfalen in Kreuztal? Wie haben sich die Verbindungen im alpenquerenden Verkehr gerade in Anbetracht der Tiroler LKW-Fahrverbote in der Region etablieren k\u00f6nnen? Was kann zur Optimierung der Anbindung der deutschen Seeh\u00e4fen noch getan werden?<\/p>\n<p>Diese und weitere Fragen standen im Mittelpunkt der Veranstaltung \u201eDIALOG.Schiene.S\u00fcdwestfalen<sup>3<\/sup>\u201c in Kreuztal. Zu der Gemeinschaftsveranstaltung hatten die KSW Kreisbahn Siegen-Wittgenstein GmbH, Hafen Hamburg Marketing e.V., DB Cargo AG, Bundesvereinigung Logistik e.V. Regionalgruppe S\u00fcdwestfalen und die IHK Siegen in die R\u00e4umlichkeiten der Krombacher Brauerei eingeladen. Rund 200 Vertreter aus Industrie, Handel, Verkehrswirtschaft sowie Verb\u00e4nden und Institutionen nutzten die Gelegenheit, um sich \u00fcber die Perspektiven und Herausforderungen im Kombinierten G\u00fcterverkehr (KV) der Region S\u00fcdwestfalen zu informieren und auszutauschen.\u00a0 \u201eDer Kombinierte Verkehr ist ein wichtiger Baustein f\u00fcr einen modernen und sauberen G\u00fcterverkehr. Mutige Investitionen wie in den Bau des neuen Container-Terminals in Kreuztal bringen die Verkehrsverlagerung voran und mehr G\u00fcter auf die Schiene,\u201c sagte Verkehrsminister Hendrik W\u00fcst.<\/p>\n<p>Gunnar Platz, Gesch\u00e4ftsf\u00fchrer der Planco Consulting GmbH, und Sebastian Doderer, Leiter Gesch\u00e4ftsbereich Logistik der EVB Eisenbahnen und Verkehrsbetriebe Elbe-Weser GmbH, informierten \u00fcber die Entwicklungschancen im KV und die Anbindung der Wirtschaftsregion S\u00fcdwestfalen an den Hamburger Hafen. Im Mittelpunkt der Pr\u00e4sentation von Dr. J\u00f6rg Hilker, Senior Vice President Industrial Sales der DB Cargo AG, standen Beispiele f\u00fcr kundenindividuelle Logistikl\u00f6sungen bei DB Cargo, welche die wachsende Bedeutung intermodaler Schienentransporte untermauerten. Dem alpenquerenden G\u00fctertransport auf der Schiene und einem gemeinsamen Res\u00fcmee der Erfahrungen aus den ersten f\u00fcnf Monaten der Zugverbindung Kreuztal &#8211; Verona widmeten sich Martin Gruber, Group CEO, GRUBER Logistics S.p.A. und Peter Dannewitz, Leiter Vertrieb der Kombiverkehr Deutsche Gesellschaft f\u00fcr kombinierten G\u00fcterverkehr mbH &amp; Co. KG.<\/p>\n<div id=\"attachment_15692\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2019\/09\/078-19-Dialog.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-15692\" class=\"size-medium wp-image-15692\" src=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2019\/09\/078-19-Dialog-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2019\/09\/078-19-Dialog-300x200.jpg 300w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2019\/09\/078-19-Dialog-768x512.jpg 768w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2019\/09\/078-19-Dialog.jpg 777w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-15692\" class=\"wp-caption-text\">Die Teilnehmer der Podiumsdiskussion (v.l.n.r.):<br \/>Martin Gruber, Group CEO, GRUBER Logistics S.p.A., Christian Betchen, Gesch\u00e4ftsf\u00fchrer, KSW Kreisbahn Siegen-Wittgenstein GmbH und S\u00fcdwestfalen Container-Terminal GmbH, Dr. J\u00f6rg Hilker, Senior Vice President Industrial Sales, DB Cargo AG, Moderatorin Beate Schmies, Studioleitung Siegen, Westdeutscher Rundfunk, Peter Dannewitz, Leiter Vertrieb, Kombiverkehr Deutsche Gesellschaft f\u00fcr kombinierten G\u00fcterverkehr mbH &amp; Co. KG, Sebastian Doderer, Leiter Gesch\u00e4ftsbereich Logistik, EVB Eisenbahnen und Verkehrsbetriebe Elbe-Weser GmbH.<\/p><\/div>\n<p>Gastgeber und Referenten sprachen sich in ihren Beitr\u00e4gen und der anschlie\u00dfenden Podiumsdiskussion, die Beate Schmies, Studioleitung Siegen des WDR, moderierte, unter anderem f\u00fcr eine Modernisierung und f\u00fcr den Ausbau einer zuverl\u00e4ssigen Schieneninfrastruktur aus. Man zeigte sich darin einig, dass neben Seecontainern auch der Transport von Einheiten mit gr\u00f6\u00dferer Ladeh\u00f6he problemlos auf der f\u00fcr die Verkehrsanbindung des Container Terminal-S\u00fcdwestfalen in Kreuztal wichtigen Ruhr-Sieg Bahnstrecke im Abschnitt Hagen-Siegen ohne gr\u00f6\u00dfere Einschr\u00e4nkungen m\u00f6glich sein m\u00fcsse. So wurde erst im August dieses Jahres die Siegstrecke auf dem Abschnitt Au-Betzdorf-Siegen f\u00fcr das KV-Profil P\/C 400 von der DB Netz AG freigegeben, wodurch sich Potenziale f\u00fcr neue Intermodalverkehre zum KV-Terminal in Kreuztal sowie Ausweichrouten f\u00fcr die bestehenden alpenquerenden Verkehre ergeben.<\/p>\n<p>Den Betrieb des neuen KV-Terminals in Kreuztal \u00fcbernehmen unter dem Namen S\u00fcdwestfalen Container-Terminal GmbH (SWCT) die Gesellschafter KSW Kreisbahn Siegen-Wittgenstein GmbH (KSW) und die Kombiverkehr Deutsche Gesellschaft f\u00fcr kombinierten G\u00fcterverkehr mbH &amp; Co. KG. F\u00fcr Christian Betchen, Gesch\u00e4ftsf\u00fchrer KSW und SWCT, erh\u00e4lt die in S\u00fcdwestfalen stark vertretene Stahl- und stahlverarbeitende Industrie mit dem neuen KV-Terminal Kreuztal bessere Verladem\u00f6glichkeiten. Neben intermodalen Verbindungen zu den deutschen und internationalen H\u00e4fen werden nach \u00dcberzeugung von Christian Betchen auch nationale KV-Verkehre und die Einbeziehung des Einzelwagenverkehrs neue und leistungsstarke Transportkonzepte f\u00fcr die Wirtschaft bringen.<\/p>\n<p>Die Gemeinschaftsveranstaltung DIALOG.Schiene.S\u00fcdwestfalen<sup>3 <\/sup>brachte auch zahlreiche Unternehmensvertreter nach Kreuztal, die sich neben den Angeboten des klassischen Wagenladungs- und Einzelwagenverkehr verst\u00e4rkt f\u00fcr intermodale Transportl\u00f6sungen interessierten die f\u00fcr Verlader ohne eigenen Gleisanschluss zugeschnitten sind. Im Zusammenhang mit dem KV-Terminal Kreuztal ergeben sich erstmals neue Chancen sowohl bei der Organisation von kontinentalen Transportketten als auch f\u00fcr maritime Seehafenhinterlandverkehre in Richtung des Hamburger Hafens.<\/p>\n<p>Markus Heinen, Leiter der Hafen Hamburg Repr\u00e4sentanz in Dortmund, wies darauf hin, dass S\u00fcdwestfalen in NRW die Industrieregion Nr. 1 sei. Verl\u00e4ssliche Routen f\u00fcr den Transport aller G\u00fcter seien f\u00fcr diese exportorientierte Wirtschaftsregion von zentraler verkehrs- und industriepolitischer Bedeutung. Der Hamburger Hafen stelle mit seiner gro\u00dfen Auswahl an weltweiten Liniendiensten f\u00fcr S\u00fcdwestfalen das Tor zur Welt dar. Aus Sicht des Hamburger Hafens haben sich nach Auffassung von Markus Heinen mit der Inbetriebnahme des neuen Container-Terminals in Kreuztal auch die M\u00f6glichkeiten einer \u00a0Anbindung der Region S\u00fcdwestfalen an Deutschlands gr\u00f6\u00dften Universalhafen seit 2018 enorm verbessert. Die Seehafen-Hinterlandverkehre des Hamburger Hafens werden von dem neuen KV-Terminal in S\u00fcdwestfalen profitieren k\u00f6nnen, ist Heinen \u00fcberzeugt: \u201eMit einem j\u00e4hrlichen Verkehrsaufkommen von rund 550.000 TEU (20-Fu\u00df-Standardcontainer) ist Nordrhein-Westfalen die zweitwichtigste Region im Container-Hinterlandverkehr des Hamburger Hafens.\u201c<\/p>\n<p>J\u00f6rg Hilker und Christian Betchen sehen mit der Betriebsaufnahme des KV-Terminals in Kreuztal gute Chancen jetzt auch verst\u00e4rkt Unternehmen der Region, die \u00fcber keinen eigenen Gleisanschluss verf\u00fcgen, auf die umweltfreundliche Schiene zu bringen. Neue Verladem\u00f6glichkeiten erhalten insbesondere Hersteller industrieller Halb- und Fertigerzeugnisse, wie beispielsweise Automobilzulieferer, aber auch Konsumg\u00fcterhersteller, wie zum Beispiel die Brauerei Krombacher. \u201eWir haben in den vergangenen Jahren immer wieder innovative und sehr kundenindividuelle intermodale Transportl\u00f6sungen entwickelt und umgesetzt. Das neue Container-Terminal in Kreuztal erweitert unsere M\u00f6glichkeiten in dieser f\u00fcr uns sehr wichtigen Wirtschaftsregion noch einmal deutlich\u201c, res\u00fcmiert J\u00f6rg Hilker. Christian Betchen erg\u00e4nzt: \u201eDiesen Unternehmen steht mit dem Container-Terminal S\u00fcdwestfalen in Kreuztal nun eine leistungsf\u00e4hige Umschlaganlage f\u00fcr Container, Wechselbr\u00fccken und Sattelauflieger im Kombinierten Verkehr Stra\u00dfe-Schiene zur Verf\u00fcgung, die eine Kapazit\u00e4t von rund 45.000 Container pro Jahr bietet\u201c.<\/p>\n<p>Der Gesch\u00e4ftsf\u00fchrer der KSW hob abschlie\u00dfend noch einmal hervor, dass Kreuztal neben der Rheinstrecke der einzige Standort s\u00fcdlich des Rhein-Ruhr-Gebietes sei, der mit dem \u201eKV Profil 400\u201c den Transport von Megatrailern und High-Cube Containern erlaube.<\/p>\n<p>Bilder und Infos: <a href=\"http:\/\/www.ksw-siegen.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">KSW Kreisbahn Siegen-Wittgenstein GmbH<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die s\u00fcdwestf\u00e4lische Wirtschaft ist auf effiziente und zuverl\u00e4ssige Verkehrsanbindungen angewiesen. Vor dem Hintergrund einer Zunahme des G\u00fcterverkehrsaufkommen und langfristigen Br\u00fcckenbauarbeiten auf den Bundesautobahnen A4 und&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[32,30,11],"tags":[],"class_list":["post-15690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos","category-vermischtes","category-regionale-wirtschaft"],"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2019\/09\/078-19-Dialog-Schiene-S\u00fcdwe.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/15690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=15690"}],"version-history":[{"count":4,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/15690\/revisions"}],"predecessor-version":[{"id":15696,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/15690\/revisions\/15696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/15691"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=15690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=15690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=15690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}