{"id":12698,"date":"2019-02-08T09:15:14","date_gmt":"2019-02-08T08:15:14","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=12698"},"modified":"2019-02-08T09:19:34","modified_gmt":"2019-02-08T08:19:34","slug":"150-jahre-volksbank-wittgenstein-eg","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/150-jahre-volksbank-wittgenstein-eg\/","title":{"rendered":"150 Jahre Volksbank Wittgenstein eG"},"content":{"rendered":"<p>Die Volksbank Wittgenstein eG mit Sitz in Bad Berleburg kann in diesem Jahr auf ihr 150-j\u00e4hriges Bestehen zur\u00fcckblicken. Gegr\u00fcndet wurde sie am 07. Februar 1869 als\u00a0\u201eDarlehenskassen-Verein f\u00fcr das Kirchspiel Berleburg, eingetragener Verein&#8220;. Ein Jahr zuvor hatte der Landwirtschaftliche Kreisverein auf Initiative von Landrat Georg Wilhelm von Schr\u00f6tter die wirtschaftliche Not in der Bev\u00f6lkerung er\u00f6tert. Als Ergebnis wurde die Gr\u00fcndung einer Bank nach dem Raiffeisenschen Vorbild beschlossen.<\/p>\n<p>Zwei Jahre sp\u00e4ter wurde der Gesch\u00e4ftsbezirk auf die Kirchspiele Raumland und Weidenhausen ausgedehnt. Zu dieser Zeit schloss sich der Verein der Westf\u00e4lischen landwirtschaftlichen Bank eGmbH mit Sitz in Iserlohn an, die die Aufgabe einer Zentralkasse \u00fcbernahm.\u00a01890 schloss sich die Bank der L\u00e4ndlichen Centralkasse eGmbH f\u00fcr die Provinz Westfalen an.\u00a0Bis 1889 wuchs die Bank auf 418 Mitglieder an. Die ruhige Entwicklung wurde durch den ersten Weltkrieg und die nachfolgende Inflation gest\u00f6rt. 1926 konnte das erste eigene Kassengeb\u00e4ude am Berleburger Bahnhof bezogen werden. Der Gesch\u00e4ftsverkehr umfasste nun auch Scheck- und Wechselzahlungen und das Wertpapiergesch\u00e4ft.<\/p>\n<p>Der Zuspruch wuchs stetig und so konnte 1934 eine Zweigstelle in Erndtebr\u00fcck er\u00f6ffnet werden. Nach den widrigen Jahren des zweiten Weltkrieges setzte sich die Aufw\u00e4rtsentwicklung fort. Dies machte es n\u00f6tig, neue Gesch\u00e4ftsr\u00e4ume zu beziehen.\u00a01966 wurde das neue Geb\u00e4ude in der Poststrasse in Berleburg bezogen. Ausserdem er\u00f6ffnete die Bank eine Zweigstelle in Diedenshausen und Berghausen.\u00a01967 wurde die im Jahre 1873 gegr\u00fcndete Spar- und Darlehenskasse Wingeshausen \u00fcbernommen.\u00a01995 wurde das Bankgeb\u00e4ude das letzte Mal umgebaut. Dies wurde am 09. Dezember gro\u00df gefeiert.\u00a01997 erfolgte schlie\u00dflich die Fusion der drei ehemaligen Volksbanken Bad Berleburg eG, Volksbank Arfeld eG und Volksbank Feudingen eG zur Volksbank Wittgenstein eG.<\/p>\n<p>Durch die B\u00fcndelung der genossenschaftlichen Bankkr\u00e4fte im heimischen Raum zeigte sich schon sehr schnell, dass die angestrebten Synergieeffekte zum Wohle der Mitglieder und Kunden Erfolg hatten.\u00a0Durch Innovation im technischen Bereich und weitere Qualifizierung der Mitarbeiter entwickelte sich die Volksbank Wittgenstein eG in den Folgejahren positiv.\u00a0Die Zahl der Mitglieder stieg konstant und so entschloss sich die Bank, Anfang 1999, die ersten Vertreterwahlen durchzuf\u00fchren. 91 stimmberechtigte Vertreter wurden f\u00fcr vier Jahre aus den Wahlbezirken Bad Berleburg, Erndtebr\u00fcck\/Wingeshausen, Arfeld und Feudingen in ihr Amt berufen. Die Mitglieder-Vertreter beschlie\u00dfen \u00fcber die Geschicke der Volksbank Wittgenstein eG in besonderem Ma\u00dfe, ihnen gegen\u00fcber legen Vorstand und Aufsichtsrat in der Vertreterversammlung Rechenschaft ab.<\/p>\n<p>Mit dem Umbau der Hauptstelle Bad Berleburg im Jahr 2000 erhielt das Geb\u00e4ude nicht nur eine neue Au\u00dfenfassade. Die Arbeitsfl\u00e4che wurde von 700 auf 1.150 Quadratmeter vergr\u00f6\u00dfert. Im Eingangsbereich wurde der Kundenservice erweitert, eine &#8222;24-Stunden-Bank&#8220; eingerichtet. Geldautomaten, Kontoauszugsdrucker, Geldrollengeber und ein Nachttresor stehen den Kunden 24 Stunden am Tag zur Verf\u00fcgung.\u00a0Die n\u00e4chste Herausforderung war die Umstellung der D-Mark auf den Euro. Am 1. Januar 2002 wurde der Euro neues gesetzliches Zahlungsmittel.\u00a0Die erste zentrale Mitgliederversammlung fand in 2009 in der Kulturhalle Dotzlar statt. 600 begeisterte Mitglieder erlebten als H\u00f6hepunkt den Vortrag des B\u00f6rsenexperten Frank Lehmann.<\/p>\n<p>Heute hat die Bank f\u00fcnf Gesch\u00e4ftsstellen mit 44 Mitarbeiterinnen und Mitarbeitern sowie f\u00fcnf Auszubildenden. Ihr geh\u00f6ren\u00a06.133 Mitglieder an. Betreut werden\u00a014.261 Kunden (Stand 01.06.2018). Die Gesch\u00e4ftsvolumen lag Ende 2017 bei 382,8 Mio. Euro, die Bilanzsumme bei 189,3 Mio. Euro.<\/p>\n<p>Neben dem Finanzgesch\u00e4ft unterst\u00fctzt die Volksbank Wittgenstein eG auch viele regionale Aktivit\u00e4ten. 2006 feierte beispielsweise Erndtebr\u00fcck das 750-j\u00e4hrige Gemeindejubil\u00e4um. Die Mitarbeiter der dortigen Filiale waren in historische Kost\u00fcme gekleidet und pr\u00e4gten vor Ort eine Jubil\u00e4umsm\u00fcnze.\u00a0Die erste Eder-Bike-Tour wurde in 2008 mit Unterst\u00fctzung der Volksbank Wittgenstein eG durchgef\u00fchrt. Viele Wittgensteiner nutzten diesen autofreien Sonntag, um sich mit Freunden und Familie per Rad oder Inlinern sportlich zu bet\u00e4tigen.<\/p>\n<p>Ebenfalls in 2008 feierte die Stadt Bad Berleburg ihr 750-j\u00e4hriges Stadtjubil\u00e4um. Die Volksbank Wittgenstein bot allen Besuchern eine Art &#8222;Zeitreise&#8220; an. Frauen und M\u00e4nner und ganz viele begeisterte Kinder schl\u00fcpften in historische Kost\u00fcme, die die Bank aus allen Zeitepochen zur Verf\u00fcgung stellte. Ein Fotograf hielt diese Gl\u00fccksmomente fest und die Bilder wurden an die Teilnehmer verschenkt.<\/p>\n<p>Die erste Messe &#8222;Wir in Wittgenstein&#8220; fand 2010 in Zusammenarbeit mit dem Immobilienpartner Rothaar-Immobilien im Industriegebiet in Schameder statt. Die erste Messe war so erfolgreich, dass im Jahr 2012 und in 2014 weitere Messen folgten. 2014 beteiligten sich 138 heimische Betriebe aus dem Bereich Handel, Handwerk und Dienstleistungen. Ca. 20.000 Besucher aus der Region und dar\u00fcber hinaus besuchten die Leistungsschau.<\/p>\n<p>Im Jubil\u00e4umsjahr veranstaltet die Volksbank Wittgenstein eG u.a. einen Fotowettbewerb.\u00a0Gesucht werden Motive, die eine \u00fcberzeugende Verbindung zur Heimatregion schaffen. Erw\u00fcnscht sind stimmungsvolle Landschaftsaufnahmen, Architekturmotive oder auch Aufnahmen, die das Leben in Wittgenstein einfangen \u2013 etwas Typisches oder auch etwas ganz Besonderes. Dem Ideenreichtum und der Gestaltung sind keine Grenzen gesetzt. Einsendeschluss ist der 1. August 2019. Au\u00dferdem vergibt die Bank 15 Mal jeweils 500 Euro f\u00fcr nachhaltige Projekte in Wittgenstein. Bewerbungen hierf\u00fcr sind bis zum 31. Oktober 2019 m\u00f6glich. Informationen zu den Jubil\u00e4umsaktionen finden Sie auf der Internetseite der <a href=\"https:\/\/www.volksbank-wittgenstein.de\/wir-fuer-sie\/ueber-uns\/jubilaeumsjahr.html\" target=\"_blank\" rel=\"noopener\">Volksbank Wittgenstein eG<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Volksbank Wittgenstein eG mit Sitz in Bad Berleburg kann in diesem Jahr auf ihr 150-j\u00e4hriges Bestehen zur\u00fcckblicken. Gegr\u00fcndet wurde sie am 07. Februar 1869&#8230;<\/p>\n","protected":false},"author":2,"featured_media":12701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,32,10],"tags":[],"class_list":["post-12698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-infos","category-unternehmen"],"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2019\/02\/vb-witti.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/12698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=12698"}],"version-history":[{"count":6,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/12698\/revisions"}],"predecessor-version":[{"id":12706,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/12698\/revisions\/12706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/12701"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=12698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=12698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=12698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}