{"id":10946,"date":"2018-09-24T08:24:59","date_gmt":"2018-09-24T06:24:59","guid":{"rendered":"https:\/\/www.vdsm.net\/wronline\/?p=10946"},"modified":"2018-09-24T08:24:59","modified_gmt":"2018-09-24T06:24:59","slug":"verkehrsminister-besucht-kirchhoff-auf-der-iaa","status":"publish","type":"post","link":"https:\/\/www.vdsm.net\/wronline\/verkehrsminister-besucht-kirchhoff-auf-der-iaa\/","title":{"rendered":"Verkehrsminister besucht KIRCHHOFF auf der IAA"},"content":{"rendered":"<p>Der Bundesminister f\u00fcr Verkehr und digitale Infrastruktur, Andreas Scheuer und der stellvertretende Ministerpr\u00e4sident von Niedersachsen, Dr. Bernd Althusmann, besuchten bei ihrem IAA Er\u00f6ffnungsrundgang zusammen mit dem Pr\u00e4sidenten des VDA, Bernhard Mattes, auch den Stand der <a href=\"https:\/\/www.kirchhoff-automotive.com\" target=\"_blank\" rel=\"noopener\">KIRCHHOFF Automotive GmbH<\/a>. Denn L\u00f6sungen f\u00fcr Elektromobilit\u00e4t, einem der Topthemen der diesj\u00e4hrigen Messe, stehen auch im Fokus des Messeauftritts von KIRCHHOFF Automotive.<\/p>\n<div id=\"attachment_10947\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2018\/09\/Minister-Scheuer-besucht-KIRCHHOFF-Automotive-Stand_IMG_0755_WEB.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10947\" class=\"wp-image-10947 size-medium\" src=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2018\/09\/Minister-Scheuer-besucht-KIRCHHOFF-Automotive-Stand_IMG_0755_WEB-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2018\/09\/Minister-Scheuer-besucht-KIRCHHOFF-Automotive-Stand_IMG_0755_WEB-300x200.jpg 300w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2018\/09\/Minister-Scheuer-besucht-KIRCHHOFF-Automotive-Stand_IMG_0755_WEB-768x512.jpg 768w, https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2018\/09\/Minister-Scheuer-besucht-KIRCHHOFF-Automotive-Stand_IMG_0755_WEB.jpg 777w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-10947\" class=\"wp-caption-text\">L\u00f6sungen f\u00fcr alternative Antriebe stehen im Vordergrund der IAA Nutzfahrzeuge in Hannover. Am Stand von KIRCHHOFF Automotive zeigte J. Wolfgang Kirchhoff, Gesch\u00e4ftsf\u00fchrender Gesellschafter der KIRCHHOFF Gruppe, Bundesverkehrsminister Andreas Scheuer innovative und wirtschaftliche Leichtbau-Konzepte f\u00fcr die sichere Unterbringung von Hochvolt-Batteriemodulen.<\/p><\/div>\n<p>\u201eDie gesamte Nutzfahrzeugindustrie ist im Aufbruch. Alle Hersteller gehen neue Wege, um den Transport der Zukunft zu gestalten\u201c, sagte VDA-Pr\u00e4sident Bernhard Mattes. Das Highlight auf dem KIRCHHOFF Automotive Messestand bildet ein skalierbares Batteriegeh\u00e4use in Leichtbauweise (Kombination aus Stahl und Aluminium) f\u00fcr elektrisch angetriebene Fahrzeuge. Zu den Besonderheiten und Vorteilen dieses Batteriegeh\u00e4uses z\u00e4hlen ein kostenoptimiertes Design, Korrosions- und Unterbodenschutz, ein integriertes K\u00fchlsystem und ein optimiertes Crashverhalten. Das innovative und wirtschaftliche Leichtbau-Konzept sorgt f\u00fcr die sichere Unterbringung von Hochvolt-Batteriemodulen. Das Geh\u00e4usedesign ist skalierbar und damit in unterschiedlichen Fahrzeugmodellen und Derivaten einsetzbar.<\/p>\n<p>Eindrucksvoll weiterentwickelt hat diesen Ansatz FAUN, ein neben KIRCHHOFF Automotive auch zur KIRCHHOFF Gruppe geh\u00f6render Gesch\u00e4ftsbereich. FAUN ist einer der europaweit f\u00fchrenden Hersteller von Abfallsammelfahrzeugen, Liftersystemen und Kehrmaschinen und hat sich \u201eZero Emission w\u00e4hrend der Entsorgung\u201c zum Ziel gesetzt. Entstanden ist aus dem gesch\u00e4ftsbereichs\u00fcbergreifenden Know-how ein selbst entwickelter elektrischer Antrieb, der zur Reichweitensteigerung Wasserstoffbrennstoffzellen- und Batterie-Technologie miteinander kombiniert. Mit dem Wasserstoff-Brennstoffzellen Fahrzeug BLUEPOWER bietet FAUN modular konfigurierbare, alternative Antriebssysteme f\u00fcr eine umweltfreundliche Entsorgungslogistik. \u201eDie Nutzfahrzeugindustrie leistet einen wesentlichen Beitrag, um die Emissionen kontinuierlich zu senken\u201c, sagte auch Bernhard Mattes.<\/p>\n<p>Dar\u00fcber hinaus pr\u00e4sentiert KIRCHHOFF Automotive einen gewichtsoptimierten Vorderachstr\u00e4ger in Aluminium-Schalenbauweise, der eine wirtschaftliche Leichtbaul\u00f6sung f\u00fcr die Serienproduktion von Montagekomponenten darstellt. Geringes Gewicht sowie die Anwendung gro\u00dfserientauglicher Produktionsprozesse wie Tiefziehen und Schutzgasschwei\u00dfen geh\u00f6ren zu den Vorteilen dieses Produktes.<\/p>\n<p>Am Beispiel eines Sto\u00dff\u00e4ngers zeigt KIRCHHOFF Automotive ein neuartiges Laserschwei\u00df-verfahren. Mit diesem Verfahren k\u00f6nnen Schwei\u00dfnahtverspr\u00f6dung vermieden, Spritzerbildung reduziert sowie Material und Gewicht eingespart werden.<\/p>\n<p>Seine Kompetenz in der modularen Fertigung beweist KIRCHHOFF Automotive beim VW Crafter. Mit drei L\u00e4ngen, drei H\u00f6hen und vier Grundmodellen spielt Vielfalt eine gro\u00dfe Rolle bei diesem Fahrzeug \u00a0und seinem nahezu baugleichen Schwestermodell MAN TGE. Wesentliche Teile der Bodengruppe \u2013 insgesamt 67 Zusammenbauten \u2013 des Crafter kommen aus dem KIRCHHOFF Automotive Werk in Gniezno, Polen. Dabei bietet ein ausgekl\u00fcgeltes Vorrichtungskonzept die Flexibilit\u00e4t, alle Varianten einer Baugruppe abzubilden.<\/p>\n<p>Mit \u00fcber 2.100 Ausstellern aus rund 50 L\u00e4ndern und \u00fcber 280.000 Quadratmetern Ausstellungsfl\u00e4che stellt die IAA Nutzfahrzeuge in diesem Jahr einen neuen Rekord auf. Noch bis zum 27. September zeigt der international t\u00e4tige Automobilzulieferer KIRCHHOFF Automotive auf der IAA Nutzfahrzeuge innovative Leichtbaul\u00f6sungen f\u00fcr Karosserie und Fahrwerk und erwartet hochrangige Vertreter der Nutzfahrzeughersteller auf seinem Stand Nr. C36 in Halle 13.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Bundesminister f\u00fcr Verkehr und digitale Infrastruktur, Andreas Scheuer und der stellvertretende Ministerpr\u00e4sident von Niedersachsen, Dr. Bernd Althusmann, besuchten bei ihrem IAA Er\u00f6ffnungsrundgang zusammen mit&#8230;<\/p>\n","protected":false},"author":6,"featured_media":10948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,10],"tags":[],"class_list":["post-10946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-unternehmen"],"jetpack_featured_media_url":"https:\/\/www.vdsm.net\/wronline\/wp-content\/uploads\/2018\/09\/Minister-Scheuer-besucht-KIRCHHOFF-Automotive-Stand_IMG_0768_WEB.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/10946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/comments?post=10946"}],"version-history":[{"count":4,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/10946\/revisions"}],"predecessor-version":[{"id":10953,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/posts\/10946\/revisions\/10953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media\/10948"}],"wp:attachment":[{"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/media?parent=10946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/categories?post=10946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vdsm.net\/wronline\/wp-json\/wp\/v2\/tags?post=10946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}